{"id":93034,"date":"2026-03-29T07:18:33","date_gmt":"2026-03-29T07:18:33","guid":{"rendered":"https:\/\/www.friaguinee.net\/?p=93034"},"modified":"2026-03-29T07:18:34","modified_gmt":"2026-03-29T07:18:34","slug":"decret-plusieurs-officiers-de-larmee-eleves-au-grade-dofficier-de-lordre-national-du-colatier","status":"publish","type":"post","link":"https:\/\/www.friaguinee.net\/index.php\/2026\/03\/29\/decret-plusieurs-officiers-de-larmee-eleves-au-grade-dofficier-de-lordre-national-du-colatier\/","title":{"rendered":"D\u00e9cret : plusieurs officiers de l\u2019arm\u00e9e \u00e9lev\u00e9s au grade d\u2019officier de l\u2019Ordre national du Colatier"},"content":{"rendered":"\n<p>\u00c0 travers un d\u00e9cret lu \u00e0 la t\u00e9l\u00e9vision nationale ce samedi 28 mars 2026, le Pr\u00e9sident de la R\u00e9publique Mamadi Doumbouya \u00e0 proc\u00e9d\u00e9 \u00e0 la nomination de plusieurs hauts officiers g\u00e9n\u00e9raux au grade d\u2019officier dans l\u2019ordre national du Collatier en r\u00e9compense des \u00e9minents et loyaux services rendus \u00e0 la Nation pour la cause de la paix, le renforcement et l\u2019\u00e9largissement des liens de coop\u00e9ration entre les peuples.<\/p>\n\n\n\n<p id=\"m_-3877514960381505229m_-5287068945159959012docs-internal-guid-ee9a0a51-7fff-dc94-4237-95a05d7863f6\">Le grade d\u2019officier de l\u2019ordre national du Collatier de la R\u00e9publique de Guin\u00e9e est d\u00e9cern\u00e9 aux officiers g\u00e9n\u00e9raux dont les pr\u00e9noms, noms et fonctions suivent :<\/p>\n\n\n\n<p id=\"m_-3877514960381505229m_-5287068945159959012docs-internal-guid-ee9a0a51-7fff-dc94-4237-95a05d7863f6\">1. G\u00e9n\u00e9ral Amara Camara, Ministre Secr\u00e9taire g\u00e9n\u00e9ral de la Pr\u00e9sidence de la R\u00e9publique;<\/p>\n\n\n\n<p id=\"m_-3877514960381505229m_-5287068945159959012docs-internal-guid-ee9a0a51-7fff-dc94-4237-95a05d7863f6\">2. G\u00e9n\u00e9ral Ahmed Mohamed Oury Diallo, ministre de la S\u00e9curit\u00e9 et de la Protection Civile;<\/p>\n\n\n\n<p id=\"m_-3877514960381505229m_-5287068945159959012docs-internal-guid-ee9a0a51-7fff-dc94-4237-95a05d7863f6\">3. G\u00e9n\u00e9ral David Haba, Directeur de cabinet du minist\u00e8re de la D\u00e9fense Nationale;<\/p>\n\n\n\n<p id=\"m_-3877514960381505229m_-5287068945159959012docs-internal-guid-ee9a0a51-7fff-dc94-4237-95a05d7863f6\">4. G\u00e9n\u00e9ral Ibrahima Sory Bangoura, chef d\u2019\u00e9tat-major g\u00e9n\u00e9ral des arm\u00e9es;<\/p>\n\n\n\n<p id=\"m_-3877514960381505229m_-5287068945159959012docs-internal-guid-ee9a0a51-7fff-dc94-4237-95a05d7863f6\">5. G\u00e9n\u00e9ral Balla Samoura, Haut-commandant de la gendarmerie nationale et directeur de la justice militaire.<\/p>\n\n\n\n<p id=\"m_-3877514960381505229m_-5287068945159959012docs-internal-guid-ee9a0a51-7fff-dc94-4237-95a05d7863f6\">Dans un autre d\u00e9cret, le pr\u00e9sident Mamadi Doumbouya a attribu\u00e9 la&nbsp;<strong>m\u00e9daille d\u2019honneur du travail dans l\u2019ordre national du m\u00e9rite<\/strong>&nbsp;au m\u00eames officiers sup\u00e9rieures except\u00e9 le G\u00e9n\u00e9ral Amara Camara.<\/p>\n\n\n\n<p><strong>Friaguinee.net<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 travers un d\u00e9cret lu \u00e0 la t\u00e9l\u00e9vision nationale ce samedi 28 mars 2026, le Pr\u00e9sident de la R\u00e9publique Mamadi Doumbouya \u00e0 proc\u00e9d\u00e9 \u00e0 la nomination de plusieurs hauts officiers g\u00e9n\u00e9raux au grade d\u2019officier dans l\u2019ordre national du Collatier en r\u00e9compense des \u00e9minents et loyaux services rendus \u00e0 la Nation pour la cause de la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":93002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-93034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/93034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=93034"}],"version-history":[{"count":2,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/93034\/revisions"}],"predecessor-version":[{"id":93036,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/93034\/revisions\/93036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/93002"}],"wp:attachment":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=93034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=93034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=93034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}