{"id":47226,"date":"2023-02-25T12:52:09","date_gmt":"2023-02-25T12:52:09","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=47226"},"modified":"2023-02-25T12:58:57","modified_gmt":"2023-02-25T12:58:57","slug":"education-fria-qui-est-mohamed-lamine-aicha-kaba-professeur-de-francais-et-auteur-du-roman-le-creux-du-ventre","status":"publish","type":"post","link":"https:\/\/www.friaguinee.net\/index.php\/2023\/02\/25\/education-fria-qui-est-mohamed-lamine-aicha-kaba-professeur-de-francais-et-auteur-du-roman-le-creux-du-ventre\/","title":{"rendered":"Education\/Fria : Qui est Mohamed Lamine A\u00efcha KABA professeur de fran\u00e7ais et auteur du roman\u00a0  \u00ab\u00a0Le creux du ventre\u201d"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-1024x768.jpg\" alt=\"\" class=\"wp-image-47234\" srcset=\"https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-1024x768.jpg 1024w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-300x225.jpg 300w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-768x576.jpg 768w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-1536x1152.jpg 1536w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-2048x1536.jpg 2048w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-80x60.jpg 80w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-265x198.jpg 265w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-696x522.jpg 696w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-1068x801.jpg 1068w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/20230225_123452_mfnr-560x420.jpg 560w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>C\u2019est un 28 septembre 1987 qu\u2019est n\u00e9 N\u2019Falamini KABA \u00e0 Conakry sous le nom de famille Mohamed Lamine A\u00efcha KABA. Fils de Soriba, commer\u00e7ant de son \u00c9tat et d\u2019A\u00efcha KABA \u00e9galement commer\u00e7ante. \u00c0 l\u2019\u00e2ge de trois ans, N\u2019Falamini fit ses premiers pas \u00e0 l\u2019\u00e9cole maternelle du groupe scolaire Mabinty Tour\u00e9.<\/p>\n\n\n\n<p>Apr\u00e8s cinq ans de parcours au primaire, N\u2019Falamini passa son premier examen national en 2000 qui s\u2019est sold\u00e9 par un succ\u00e8s. Puis, il eut successivement son Brevet d\u2019\u00e9tude du premier cycle en 2005 et son baccalaur\u00e9at unique en 2008 au groupe scolaire IVR campus entendez, Institut de valorisation<\/p>\n\n\n\n<p>des ressources.<\/p>\n\n\n\n<p>Ayant pour r\u00eave de devenir avocat, N\u2019Falamini atterrit \u00e0 l\u2019Universit\u00e9 Julius Nyerere de Kankan dans la facult\u00e9 des Langues et Lettres, notamment au d\u00e9partement linguistique o\u00f9 il obtient son dipl\u00f4me de Licence en 2012 avec la mention Tr\u00e8s bien.<\/p>\n\n\n\n<p>Cependant, poursuivant son r\u00eave de faire des \u00e9tudes de Droit, il s&rsquo; inscrit \u00e0 l\u2019Institut Sup\u00e9rieur de Formation \u00e0 distance obtienten 2013, une Licence en Droit civil avec une mention Assez bien.<\/p>\n\n\n\n<p>En octobre 2012, N\u2019Falamini se lan\u00e7a dans l\u2019enseignement de la langue fran\u00e7aise dans les \u00e9coles priv\u00e9es, dans premier temps \u00e0 Conakry (Massaran Keita \u00e0 Tombolia et Hadja Fatou Gu\u00e8ye \u00e0 kissosso). Puis, il fut recrut\u00e9 \u00e0 la Fonction Publique par voie de concours organis\u00e9e en 2013, et mis \u00e0 la disposition du Minist\u00e8re de l\u2019Enseignement Pr\u00e9-universitaire et qui, \u00e0 son tour, l\u2019affecta \u00e0 la Direction Pr\u00e9fectorale de l\u2019Education de Fria pour servir au lyc\u00e9e Amilcar Cabral comme professeur de fran\u00e7ais dans les classes Terminales Sciences sociales o\u00f9 il rendit de loyaux services durant huit ans avant d\u2019\u00eatre mut\u00e9 au coll\u00e8ge\/lyc\u00e9e Josip-Broz Tito o\u00f9 il sert avec brio d\u2019il y a deux ans.<\/p>\n\n\n\n<p>Pour finir, N\u2019Falamini KABA est certifi\u00e9 formateur des formateurs en langue fran\u00e7aise et en p\u00e9dagogie du fran\u00e7ais, une formation assur\u00e9e par l\u2019ambassade de France de 2020 \u00e0 2021 dans le cadre du programme d\u2019appui sectoriel \u00e0 la diffusion et la ma\u00eetrise du fran\u00e7ais.&nbsp;<\/p>\n\n\n\n<p>Et aujourd\u2019hui, il est officiellement inscrit comme auteur du roman \u00a0\u00bb&nbsp; Le creux du ventre\u201d dans le registre des \u00e9crivains de Guin\u00e9e et d\u2019Afrique noire, ainsi que du monde.<\/p>\n\n\n\n<p>Amoureux de la lecture et aimant \u00e9crire, N\u2019Falamini KABA pendant qu\u2019il \u00e9tait \u00e0 l\u2019universit\u00e9 affichait son d\u00e9sarroi face \u00e0 la pauvret\u00e9, la souffrance et de l\u2019abandon des enfants par le gouvernement d\u2019alors et dont ces fl\u00e9aux sont souvent source de d\u00e9mission scolaire er d\u2019orientation pour les enfants vers des chemins de r\u00e9ussite incertaine.<\/p>\n\n\n\n<p>Ainsi pour mieux transmettre son message, Mohamed Lamine A\u00efcha KABA s\u2019est inspir\u00e9 du parcours risqu\u00e9 et courageux du jeune Sitanmadi qui va tr\u00e8s t\u00f4t abandonner l\u2019\u00e9cole dans le but d\u2019aider sa m\u00e8re \u00e0 sortir de la pauvret\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n-1024x576.jpg\" alt=\"\" class=\"wp-image-47231\" srcset=\"https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n-1024x576.jpg 1024w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n-300x169.jpg 300w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n-768x432.jpg 768w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n-1536x864.jpg 1536w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n-696x392.jpg 696w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n-1068x601.jpg 1068w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n-747x420.jpg 747w, https:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/02\/328398595_1827072920982402_897852630343565767_n.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>C\u2019est pourquoi pendant l\u2019universit\u00e9 en 2009, et passant des nuits blanches \u00e0 \u00e9crire Mohamed Lamine A\u00efcha KABA&nbsp; fini par atteindre ses objectifs avec l\u2019appui&nbsp; des \u00e9ditions YIGUI, pour afin d\u00e9cider de d\u00e9dicacer son roman intitul\u00e9 \u201c Le creux du vente \u201c ce samedi 25 f\u00e9vrier 2023 dans la salle de d\u00e9lib\u00e9ration de la commune urbaine de Fria, en pr\u00e9sence des autorit\u00e9s pr\u00e9fectorales et communale, de Monsieur Abdoul Karim Tour\u00e9 Directeur Pr\u00e9fectoral de l\u2019Education de Fria, des cadres de la DPE, des enseignants, de sa famille, des amis, des \u00e9l\u00e8ves venus des diff\u00e9rents \u00e9tablissements de la commune urbaine de Fria.<\/p>\n\n\n\n<p><strong>Fana Koba Ciss\u00e9 pour Friaguinee.net<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est un 28 septembre 1987 qu\u2019est n\u00e9 N\u2019Falamini KABA \u00e0 Conakry sous le nom de famille Mohamed Lamine A\u00efcha KABA. Fils de Soriba, commer\u00e7ant de son \u00c9tat et d\u2019A\u00efcha KABA \u00e9galement commer\u00e7ante. \u00c0 l\u2019\u00e2ge de trois ans, N\u2019Falamini fit ses premiers pas \u00e0 l\u2019\u00e9cole maternelle du groupe scolaire Mabinty Tour\u00e9. Apr\u00e8s cinq ans de parcours [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":47228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-47226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education"],"_links":{"self":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/47226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=47226"}],"version-history":[{"count":2,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/47226\/revisions"}],"predecessor-version":[{"id":47235,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/47226\/revisions\/47235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/47228"}],"wp:attachment":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=47226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=47226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=47226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}