{"id":39672,"date":"2021-10-22T17:35:31","date_gmt":"2021-10-22T17:35:31","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=39672"},"modified":"2021-10-22T17:35:32","modified_gmt":"2021-10-22T17:35:32","slug":"syli-national-feminin-antonio-souare-offre-100-millions-a-lequipe","status":"publish","type":"post","link":"https:\/\/www.friaguinee.net\/index.php\/2021\/10\/22\/syli-national-feminin-antonio-souare-offre-100-millions-a-lequipe\/","title":{"rendered":"Syli National f\u00e9minin : Antonio Souar\u00e9 offre 100 millions \u00e0 l\u2019\u00e9quipe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Conform\u00e9ment \u00e0 sa promesse tenue apr\u00e8s la qualification du Syli National F\u00e9minin U-20 pour le troisi\u00e8me tour des \u00e9liminatoires du Mondial, Costa Rica 2022, le Pr\u00e9sident de la F\u00e9d\u00e9ration Guin\u00e9enne de Football, Mamadou Antonio Souar\u00e9, vient d&rsquo;offrir 100 millions de Francs guin\u00e9ens aux joueuses et \u00e0 leurs encadreurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La c\u00e9r\u00e9monie de remise du montant s&rsquo;est d\u00e9roul\u00e9e ce vendredi 22 octobre au si\u00e8ge de la FEGUIFOOT, en pr\u00e9sence de quelques membres du Comit\u00e9 ex\u00e9cutif et du Secr\u00e9taire G\u00e9n\u00e9ral de l&rsquo;Institution.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cette occasion, Maurice Ako\u00ef Ko\u00efvogui n&rsquo;a pas manqu\u00e9 de saluer ce grand geste du Pr\u00e9sident Antonio Souar\u00e9 qui, selon lui, permet de motiver davantage le Syli National F\u00e9minin U-20 en vue des prochaines \u00e9ch\u00e9ances.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour sa part, la S\u00e9lectionneure C\u00e9cile Kourouma a adress\u00e9 ses sinc\u00e8res remerciements au donateur, avant de laisser entendre que le football f\u00e9minin est sur le point d&rsquo;atteindre les r\u00e9sultats escompt\u00e9s en Guin\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">FGF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conform\u00e9ment \u00e0 sa promesse tenue apr\u00e8s la qualification du Syli National F\u00e9minin U-20 pour le troisi\u00e8me tour des \u00e9liminatoires du Mondial, Costa Rica 2022, le Pr\u00e9sident de la F\u00e9d\u00e9ration Guin\u00e9enne de Football, Mamadou Antonio Souar\u00e9, vient d&rsquo;offrir 100 millions de Francs guin\u00e9ens aux joueuses et \u00e0 leurs encadreurs. La c\u00e9r\u00e9monie de remise du montant s&rsquo;est [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":39673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[3928,2009,148,8384],"class_list":["post-39672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-100-millions","tag-antonio-souare","tag-guinee","tag-syli-feminin"],"_links":{"self":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/39672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=39672"}],"version-history":[{"count":1,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/39672\/revisions"}],"predecessor-version":[{"id":39674,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/39672\/revisions\/39674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/39673"}],"wp:attachment":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=39672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=39672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=39672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}