{"id":38450,"date":"2021-09-17T12:47:49","date_gmt":"2021-09-17T12:47:49","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=38450"},"modified":"2021-09-17T19:29:23","modified_gmt":"2021-09-17T19:29:23","slug":"coup-detat-en-guinee-je-supplie-le-peuple-de-guinee-de-radicalement-changer-de-mentalite-et-se-mettre-au-travail-robert-sarah-lettre","status":"publish","type":"post","link":"https:\/\/www.friaguinee.net\/index.php\/2021\/09\/17\/coup-detat-en-guinee-je-supplie-le-peuple-de-guinee-de-radicalement-changer-de-mentalite-et-se-mettre-au-travail-robert-sarah-lettre\/","title":{"rendered":"Coup d\u2019Etat en Guin\u00e9e : \u00ab Je supplie le peuple de Guin\u00e9e de radicalement changer de mentalit\u00e9 et se mettre au travail \u00bbRobert Sarah (lettre)"},"content":{"rendered":"\n<p>A travers une lettre adress\u00e9e au pr\u00e9sident du CNRD le colonel Mamady Doumbouya, le &nbsp;Cardinal &nbsp;Robert Sarah \u00ab&nbsp;supplie le peuple de Guin\u00e9e de radicalement changer de mentalit\u00e9 et d\u2019habitudes et de se mettre au travail&nbsp;\u00bb.<\/p>\n\n\n\n<p><em>&nbsp;<\/em>Excellence,\nMonsieur le Pr\u00e9sident,<\/p>\n\n\n\n<p> Nous avons appris la prise du pouvoir par le CNRD, ce 5 septembre 2021. L\u2019histoire se r\u00e9p\u00e8te.<\/p>\n\n\n\n<p>Comme en 1984 et en 2008, la population guin\u00e9enne est sortie dans la rue pour exprimer sa joie parce que l\u2019acte que vous avez pos\u00e9 suscite de l\u2019espoir, encore une fois : espoir de justice, de paix, de redressement r\u00e9el et de d\u00e9veloppement, espoir de vivre tout simplement dans un pays normal, une Nation unie et prosp\u00e8re.<\/p>\n\n\n\n<p>Il faut cependant constater, h\u00e9las, que les deux exp\u00e9riences\npr\u00e9c\u00e9dentes de prise du pouvoir par l\u2019arm\u00e9e, n\u2019ont pas permis de cr\u00e9er les\nbases de la refondation de la Nation et la construction d\u2019un Etat de droit.<\/p>\n\n\n\n<p>Ce qui a conduit la Guin\u00e9e dans une situation de pauvret\u00e9\naccrue, malgr\u00e9 toutes les richesses naturelles que Dieu lui a donn\u00e9es.<\/p>\n\n\n\n<p>Depuis plus de cinquante ans, la Guin\u00e9e descend inexorablement\ndans les profondeurs du sous- d\u00e9veloppement et de la mis\u00e8re end\u00e9mique, et le\npeuple de Guin\u00e9e ne fait que subir d\u00e9ception sur d\u00e9ception.<\/p>\n\n\n\n<p>Vous avez aujourd\u2019hui cr\u00e9\u00e9 les conditions propices \u00e0 la remise\nen question de la voie que le pays a suivie jusqu\u2019\u00e0 pr\u00e9sent, et qui n\u2019a pas\napport\u00e9 le bonheur que les guin\u00e9ens esp\u00e9raient.<\/p>\n\n\n\n<p>La page est redevenue blanche.<br>\nLes Guin\u00e9ens n\u2019ont plus droit \u00e0 l\u2019erreur.<\/p>\n\n\n\n<p>Les bonnes paroles que vous avez prononc\u00e9es doivent \u00eatre\ntransform\u00e9es en actes concrets pour construire une Guin\u00e9e nouvelle.<\/p>\n\n\n\n<p>Mais Il vous faudra beaucoup de v\u00e9rit\u00e9 et de courage, d\u2019h\u00e9ro\u00efsme\net de d\u00e9termination pour balayer autour de vous tous les pr\u00e9dateurs inv\u00e9t\u00e9r\u00e9s\nde notre Pays, corrompus et incomp\u00e9tents qui ont accompagn\u00e9 les gouvernements\nde S\u00e9kou Tour\u00e9, Lansana Cont\u00e9, Moussa Dadis Camara et Alpha Cond\u00e9, et qui se\nconsid\u00e8rent comme des \u00e9l\u00e9ments incontournables et inamovibles.<\/p>\n\n\n\n<p>Le redressement et le d\u00e9veloppement que vous voulez initier ne\npourra jamais voir le jour, si vous ne changez pas radicalement l\u2019ambiance et\nl\u2019environnement du gouvernement guin\u00e9en.<\/p>\n\n\n\n<p>\u00ab Personne ne coud une pi\u00e8ce de drap non foul\u00e9 \u00e0 un vieux\nv\u00eatement, autrement, la pi\u00e8ce neuve tire sur le vieux v\u00eatement et la d\u00e9chirure\ns\u2019aggrave. \u00bb (Mc 2,21-22).<\/p>\n\n\n\n<p>Pour le bien de la Guin\u00e9e, travaillez de toutes vos \u00e9nergies \u00e0\nrenouveler la classe politique. Ne permettez plus que les leaders politiques\nabusent de notre peuple et le manipulent au gr\u00e9 de leurs int\u00e9r\u00eats \u00e9go\u00efstes.<\/p>\n\n\n\n<p>Il faut pour notre Pays une nouvelle g\u00e9n\u00e9ration de leaders\npolitiques qui aiment leur pays et leurs concitoyens et unissent leurs forces\npour la paix, l\u2019unit\u00e9 et le d\u00e9veloppement des Guin\u00e9ens, au lieu de les inciter\n\u00e0 se ha\u00efr et \u00e0 s\u2019entretuer.<\/p>\n\n\n\n<p>Que les leaders politiques guin\u00e9ens qui ont oppos\u00e9 les ethnies\net les r\u00e9gions les unes contre les autres et ont cloisonn\u00e9 les Guin\u00e9ens en\npartis politiques pour les dresser les uns contre les autres arr\u00eatent cette\npratique diabolique qui paralyse et d\u00e9truit le Pays.<\/p>\n\n\n\n<p>Vous avez dit vous-m\u00eame, Mr le Pr\u00e9sident, en citant Jerry\nRawlings, \u00ab&nbsp;Si le peuple est \u00e9cras\u00e9 par ses \u00e9lites, il revient \u00e0 l\u2019arm\u00e9e\nde rendre au peuple sa libert\u00e9 \u00ab. Oui, redonnez au peuple non seulement sa\nlibert\u00e9, mais surtout la sant\u00e9 physique et morale, une vie plus digne et un peu\nde bonheur. Soyez extr\u00eamement s\u00e9v\u00e8re envers les militaires qui voudraient\nprofiter de l\u2019accession au pouvoir par l\u2019arm\u00e9e pour s\u2019enrichir au d\u00e9triment du\npeuple.&nbsp;\u00bb<\/p>\n\n\n\n<p>La Guin\u00e9e est b\u00e9nie d\u2019une pluviom\u00e9trie abondante, d\u2019une richesse\ndu sous-sol exceptionnelle. Mais sa population manque tragiquement d\u2019eau\npotable et d\u2019\u00e9lectricit\u00e9, et trouve difficilement de quoi se nourrir dignement.<\/p>\n\n\n\n<p>L\u2019\u00e9cole et l\u2019\u00e9ducation sont en faillite.<br>\nLa sant\u00e9 est dans une d\u00e9plorable d\u00e9gradation.<br>\nLes infrastructures routi\u00e8res sont catastrophiques.<br>\nLa corruption, la gabegie financi\u00e8re, le manque total de discipline morale et\n\u00e9thique, la<br>\nm\u00e9diocrit\u00e9 et l\u2019incomp\u00e9tence chronique font croupir la Guin\u00e9e dans la mis\u00e8re et\nla d\u00e9cadence de la vie sociale.<\/p>\n\n\n\n<p>Comment sortir de cette impasse ?<\/p>\n\n\n\n<p>Utilisez votre intelligence et vos capacit\u00e9s d\u2019analyse objective\nde notre histoire, de nos mentalit\u00e9s et de nos nombreuses erreurs.<br>\nMais surtout approchez vos fr\u00e8res et s\u0153urs comp\u00e9tents, capables et int\u00e8gres\npour vous accompagner.<\/p>\n\n\n\n<p>Prenez le temps qu\u2019il faut pour la r\u00e9flexion, l\u2019analyse, la\nconcertation et l\u2019action vraie et juste afin d\u2019\u00e9viter les erreurs du pass\u00e9.<\/p>\n\n\n\n<p>C\u2019est une chance nouvelle pour le Pays. Nous ne devons pas la\nlaisser passer.<\/p>\n\n\n\n<p>C\u2019est l\u2019occasion de changer radicalement le cours de l\u2019histoire\nen permettant enfin au Pays d\u2019amorcer une nouvelle marche vers ce qui est bien\net bon pour lui.<\/p>\n\n\n\n<p>Chaque Pays a son histoire, ses d\u00e9fis \u00e0 relever, ses erreurs \u00e0\ncombattre et \u00e0 corriger, sa population \u00e0 \u00e9duquer, son rythme de marche.<\/p>\n\n\n\n<p>R\u00e9sistez avec fermet\u00e9, sagesse et intelligence aux pressions de\nceux dont la seule pr\u00e9occupation est de voir des processus politiques mis en\n\u0153uvre le plus rapidement possible pour leurs int\u00e9r\u00eats inavou\u00e9s, et au d\u00e9triment\ndes populations guin\u00e9ennes.<\/p>\n\n\n\n<p>Avant d\u2019envisager des \u00e9lections pr\u00e9sidentielles, posez d\u2019abord\nles fondations d\u2019une \u00e9conomie solide, d\u2019une soci\u00e9t\u00e9 unie, solidaire et capable\nde d\u00e9veloppement par le travail.<\/p>\n\n\n\n<p>En effet pour que l\u2019immeuble soit solide face aux intemp\u00e9ries,\nle soubassement doit \u00eatre r\u00e9sistant \u00e0 toute \u00e9preuve.<\/p>\n\n\n\n<p>Attelez-vous \u00e0 sa construction dans les r\u00e8gles de l\u2019art.<\/p>\n\n\n\n<p>Vous sauverez le Pays en laissant votre nom dans l\u2019histoire.<\/p>\n\n\n\n<p>Les Guin\u00e9ens vous en seront infiniment reconnaissants.<\/p>\n\n\n\n<p>Aussi je fais appel \u00e0 tous mes compatriotes guin\u00e9ens qui sont \u00e0\nl\u2019\u00e9tranger ou en Guin\u00e9e et<br>\nqui ont acquis de hautes qualifications et comp\u00e9tences professionnelles dans\ndes structures ou organisations internationales, d\u2019accepter de se donner la\nmain, en oubliant leurs origines ethniques ou r\u00e9gionales et de consentir tous\nles sacrifices n\u00e9cessaires afin de sortir la Guin\u00e9e de la catastrophe\n\u00e9conomique et des fractures sociales.<\/p>\n\n\n\n<p>Je supplie le peuple de Guin\u00e9e de radicalement changer de\nmentalit\u00e9 et d\u2019habitudes et de se mettre au travail.<\/p>\n\n\n\n<p>Je demande aux Guin\u00e9ens de refuser d\u00e9sormais qu\u2019on vous mette\ndans la rue pour manifester et vous inciter \u00e0 vous entretuer.<\/p>\n\n\n\n<p>Votre bonheur, c\u2019est vous qui le construisez par votre travail\net vos efforts quotidiens.<\/p>\n\n\n\n<p>Aucun gouvernement, aucun chef d\u2019\u00e9tat, aucun leader politique ne\nvous apportera le bonheur sur un plateau en or, sans votre travail r\u00e9el et\nvotre ferme d\u00e9termination \u00e0 sortir de la mis\u00e8re mat\u00e9rielle et morale.<\/p>\n\n\n\n<p>Je ne peux terminer ce message sans vous demander\nrespectueusement, Monsieur le Pr\u00e9sident du CNRD, de traiter dignement Mr le\nPr\u00e9sident Alpha Cond\u00e9 et de le lib\u00e9rer le plus vite que possible.<\/p>\n\n\n\n<p>Soyez assur\u00e9, Monsieur le Pr\u00e9sident, que la Guin\u00e9e et nos\npopulations sont dans mes pri\u00e8res quotidiennes.<\/p>\n\n\n\n<p>Que Dieu b\u00e9nisse la Guin\u00e9e !<br>\n<strong>Robert Sarah<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;Cardinal Cit\u00e9 du Vatican <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A travers une lettre adress\u00e9e au pr\u00e9sident du CNRD le colonel Mamady Doumbouya, le &nbsp;Cardinal &nbsp;Robert Sarah \u00ab&nbsp;supplie le peuple de Guin\u00e9e de radicalement changer de mentalit\u00e9 et d\u2019habitudes et de se mettre au travail&nbsp;\u00bb. &nbsp;Excellence, Monsieur le Pr\u00e9sident, Nous avons appris la prise du pouvoir par le CNRD, ce 5 septembre 2021. L\u2019histoire se [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":38451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[8105,8104],"class_list":["post-38450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-lettte","tag-robert-sarrah"],"_links":{"self":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/38450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=38450"}],"version-history":[{"count":2,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/38450\/revisions"}],"predecessor-version":[{"id":38455,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/38450\/revisions\/38455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/38451"}],"wp:attachment":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=38450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=38450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=38450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}