{"id":37293,"date":"2021-08-14T08:54:47","date_gmt":"2021-08-14T08:54:47","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=37293"},"modified":"2021-08-14T08:54:49","modified_gmt":"2021-08-14T08:54:49","slug":"musique-affaire-mboma-quest-ce-qui-fait-sa-particularite-ousmane-bangoura","status":"publish","type":"post","link":"https:\/\/www.friaguinee.net\/index.php\/2021\/08\/14\/musique-affaire-mboma-quest-ce-qui-fait-sa-particularite-ousmane-bangoura\/","title":{"rendered":"Musique\/Affaire M&rsquo;Boma : \u00ab\u00a0Qu&rsquo;est-ce qui fait sa particularit\u00e9 ?\u00a0\u00bb(Ousmane Bangoura)"},"content":{"rendered":"\n<p>Le chanteur Mboma appelle les hommes au plaisir sexuel paroxystique. C\u2019est-\u00e0-dire le plaisir absolu, le point culminant de la satisfaction, le dernier degr\u00e9 si vous le voulez.<\/p>\n\n\n\n<p>\u00ab Wadou ha Gnonah \u00bb, c\u2019est le titre du morceau. C\u2019est en poular, \u00e7a veut dire \u00ab Faites jusqu\u2019\u00e0 la satisfaction \u00bb en parlant bien \u00e9videmment de la sexualit\u00e9. <\/p>\n\n\n\n<p>En v\u00e9rit\u00e9, la vulgarit\u00e9 sonore n\u2019est pas une nouveaut\u00e9 dans l\u2019industrie musicale guin\u00e9enne. Si je ne m\u2019abuse, l\u2019histoire remonte m\u00eame du groupe \u00abB &#8211; TULO \u00bb avec le titre AYIB\u00d6 qui veut dire en soussous \u00ab D\u00e9chire le \u00bb toujours en parlant du sexe. <\/p>\n\n\n\n<p>Ce n\u2019est que quelques ann\u00e9es plus tard que DJAMAN, l\u2019ic\u00f4ne m\u00eame de la vulgarit\u00e9 musicale a repris le flambeau avec le titre \u00ab Soukoundaye \u00bb. Il sera ensuite suivi de plusieurs autres musiques d\u00e9mystificatrices de la sexualit\u00e9, un sujet encore tr\u00e8s tabou dans la soci\u00e9t\u00e9 guin\u00e9enne. <\/p>\n\n\n\n<p>De #Patampass de TAKANA ZION en passant par #Wadoum\u00f6 de King Salamane du groupe BANLIEUZ&rsquo;ART OFFICIEL jusqu\u2019\u00e0 Jungle noun Koumi d\u2019 Instinct Killers, jamais les injures n\u2019ont aussi r\u00e9sonn\u00e9 dans les oreilles des m\u00e9lomanes guin\u00e9ens. <\/p>\n\n\n\n<p>QU\u2019EST-CE QUI FAIT LA PARTICULARIT\u00c9 DE M\u2019BOMA DONC ? <\/p>\n\n\n\n<p>Sous contr\u00f4le de ceux qui comprennent et qui parlent bien le poular, je pense que c\u2019est son aspect appel \u00e0 la p\u00e9dophilie. Lorsqu\u2019il dit par exemple: <\/p>\n\n\n\n<p>\u00ab Quand une fille de 10 ans se donne \u00e0 toi, il faut le faire, il faut la baiser jusqu\u2019\u00e0 la satisfaction absolue. Tu ne sais pas si tu auras une autre occasion demain\u2026 \u00bb. <\/p>\n\n\n\n<p>Dans un contexte marqu\u00e9 par une guerre sans merci d\u00e9clar\u00e9e aux violences sexuelles par les d\u00e9fenseurs de bonnes m\u0153urs, cette chanson ne pourra pas passer inaper\u00e7ue. Elle va \u00e0 l\u2019encontre des multiples actions de sensibilisation contre les violences bas\u00e9es sur le genre. <\/p>\n\n\n\n<p>O\u00d9 CE TROUVE LA D\u00c9FAILLANCE ? <\/p>\n\n\n\n<p>D\u2019abord au niveau des autorit\u00e9s. Normalement, le Bureau Guin\u00e9en des Droits d\u2019Auteur (BGDA) dispose une cellule d\u2019\u00e9coute. Elle doit fonctionner comme un laboratoire o\u00f9 se font diagnostiquer les nouveaux morceaux avant d\u2019\u00eatre mis \u00e0 la disposition du public. Cela permettrait non seulement \u00e0 identifier les plagiats, mais aussi \u00e0 veiller sur le respect de l\u2019\u00e9thique et de la d\u00e9ontologie de la musique. <\/p>\n\n\n\n<p>Cette cellule existe bel et  bien mais est-ce qu\u2019elle fonctionne normalement ? <\/p>\n\n\n\n<p>Nous ne sommes plus dans les ann\u00e9es 80 o\u00f9 les studios d\u2019enregistrement \u00e9taient rarement compt\u00e9s sur le continent. Avec cette \u00e8re num\u00e9rique, les chansons sont fabriqu\u00e9es m\u00eames \u00e0 partir d\u2019un t\u00e9l\u00e9phone. <\/p>\n\n\n\n<p>En suite les artistes, une production musicale devrait refl\u00e9ter les valeurs soci\u00e9tales. Avant de composer une chanson, il est important que vous preniez conscience qu\u2019elle sera \u00e9cout\u00e9e par tout le monde. Par vos m\u00e8res, p\u00e8res, fils, filles, s\u0153urs, fr\u00e8res etc. Soignez les contenus avant tout. Mais que dire m\u00eame si les gens trouvent du plaisir \u00e0 \u00e9couter les insanit\u00e9s ? <\/p>\n\n\n\n<p>MON AVIS <\/p>\n\n\n\n<p>Bien que ce ne soit pas une nouveaut\u00e9, arr\u00eatons de dire que l\u2019artiste Mboma ne doit pas \u00eatre sanctionn\u00e9. Certes les uns ont commenc\u00e9 avant lui, mais s\u2019il peut servir d\u2019exemple pour que le ph\u00e9nom\u00e8ne s\u2019arr\u00eate \u00e0 lui, tant mieux. Ce n\u2019est pas parce que X a tu\u00e9 qu\u2019on devrait permettre \u00e0 Y de le faire. <\/p>\n\n\n\n<p><strong>Ousmane Bangoura <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le chanteur Mboma appelle les hommes au plaisir sexuel paroxystique. C\u2019est-\u00e0-dire le plaisir absolu, le point culminant de la satisfaction, le dernier degr\u00e9 si vous le voulez. \u00ab Wadou ha Gnonah \u00bb, c\u2019est le titre du morceau. C\u2019est en poular, \u00e7a veut dire \u00ab Faites jusqu\u2019\u00e0 la satisfaction \u00bb en parlant bien \u00e9videmment de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,153],"tags":[799,148,7837,7839],"class_list":["post-37293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","category-opinion","tag-culture","tag-guinee","tag-musique","tag-pedophilie"],"_links":{"self":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/37293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=37293"}],"version-history":[{"count":1,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/37293\/revisions"}],"predecessor-version":[{"id":37297,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/37293\/revisions\/37297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/37295"}],"wp:attachment":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=37293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=37293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=37293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}