{"id":33487,"date":"2021-05-08T17:10:52","date_gmt":"2021-05-08T17:10:52","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=33487"},"modified":"2021-05-08T17:10:53","modified_gmt":"2021-05-08T17:10:53","slug":"conakry-le-projet-himo-lance-par-le-curage-des-caniveaux","status":"publish","type":"post","link":"https:\/\/www.friaguinee.net\/index.php\/2021\/05\/08\/conakry-le-projet-himo-lance-par-le-curage-des-caniveaux\/","title":{"rendered":"Conakry : le projet HIMO lanc\u00e9 par le curage des caniveaux"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans le cadre de l\u2019initiative pre\u0301sidentielle de cre\u0301ation d\u2019emplois me\u0302me temporaires et de redistribution du revenu national, le choix est fait de les transformer en projets HIMO (haute intensite\u0301 de main d\u2019\u0153uvre), dans le cadre d\u2019un programme pilote de brigades d\u2019entretien des routes, initie\u0301es par Madame la Ministre des Travaux Publics. Ces contrats sont conc\u0327us pour des entreprises individuelles pour l\u2019Assainissement et Curage de caniveaux de Conakry.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce projet est divise\u0301 en deux grands volets : le volet curage des caniveaux (1) et le volet Balayage des principales voies routie\u0300res de Conakry   (2)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volet Curage des Caniveaux : dans ce volet, 109 contrats d\u2019assainissement sont signe\u0301s pour une enveloppe globale de GNF 16 Milliards trois cent cinquante millions (GNF 16.350.000.000) soit GNF 150 000 000 par contrat.<br>\nParlant de la modalite\u0301 d\u2019exe\u0301cution du contrat,  pre\u0301cisons que le promoteur principal be\u0301ne\u0301ficie de GNF 30 000 000 au titre de la supervision du projet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ce qui concernant son co\u0302te\u0301 employabilite\u0301, 20 a\u0300 25 jeunes (en fonction de la longueur et de la difficulte\u0301 de la zone d\u2019intervention) sont recrute\u0301s a\u0300 travers les associations et mouvements de jeunes dans la zone d\u2019intervention par les Communes et la DNER (Directions communales des jeunes et des TP).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les 25 jeunes seront re\u0301mune\u0301re\u0301s pendant 4 mois pour un montant global de GNF 70.000.000 soit GNF 700.000 par jeune et par mois.<br>\nLe ramassage des ordures par des camions est assure\u0301 par l\u2019ANSP et les communes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les frais d\u2019intendance et de logistique pour le recrutement des jeunes, la formation en technique HIMO et entreprenariat, le ramassage et le transport des ordures, la communication ainsi que le suivi et le contro\u0302le (Communes et DRTP Conakry): forfait de 10 millions par contrat selon des modalite\u0301s a\u0300 de\u0301finir pour une dure\u0301e de 4 mois<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Re\u0301sultats attendus: <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 pour 109 contrats, 2.725  jeunes be\u0301ne\u0301ficient en 4 mois d\u2019un revenu de 700.000 GNF par mois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 109 petits entrepreneurs obtiennent un revenu total net d\u2019impo\u0302t de GNF 30.000.000 chacun.<br>\n\u2022 Des revenus indirects (proprie\u0301taires de camions, chauffeurs, employe\u0301s communaux, journalistes, formateurs, contro\u0302leurs) sont cre\u0301e\u0301s pour environ 100 personnes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volet 2 : Balayage des principales voies routie\u0300res de Conakry<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De braves femmes de Conakry, souvent tre\u0300s vieilles s\u2019investissent depuis des anne\u0301es pour balayer les principales routes de Conakry (de\u0301sensablement notamment). Elles sont structure\u0301es pour certaines par le Gouvernorat ou quelques Mairies, avec un certain revenu mensuel. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cadre du HIMO de ce projet, il s\u2019agit d\u2019utiliser aussi ces femmes, qui pour la majorite\u0301, sont les piliers de leurs familles respectives en pre\u0301voyant en plus, pour les plus me\u0301ritantes un petit fonds de commerce pour une activite\u0301 ge\u0301ne\u0301ratrice de revenus, a\u0300 la fin du projet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En accord avec les Communes et le Gouvernorat, et sur la base des voies a\u0300 balayer (Autoroute et route le Prince pour les autres Communes, principales arte\u0300res pour Kaloum), 1.500 femmes sont utilise\u0301es pour cette activite\u0301 pendant 4mois ou\u0300 chaque femme recevra 500.000 GNF par mois, soit un montant total de GNF 3.000.000.000.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">FER<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de l\u2019initiative pre\u0301sidentielle de cre\u0301ation d\u2019emplois me\u0302me temporaires et de redistribution du revenu national, le choix est fait de les transformer en projets HIMO (haute intensite\u0301 de main d\u2019\u0153uvre), dans le cadre d\u2019un programme pilote de brigades d\u2019entretien des routes, initie\u0301es par Madame la Ministre des Travaux Publics. Ces contrats sont conc\u0327us [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33489,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[50,6938,4469,3526,6937],"class_list":["post-33487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-conakry","tag-curage-de-caniveaux","tag-ministere-de-la-jeunesse","tag-ministere-des-travaux-publics","tag-projet-himo"],"_links":{"self":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/33487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=33487"}],"version-history":[{"count":2,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/33487\/revisions"}],"predecessor-version":[{"id":33490,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/33487\/revisions\/33490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/33489"}],"wp:attachment":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=33487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=33487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=33487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}