{"id":20587,"date":"2020-06-01T21:36:02","date_gmt":"2020-06-01T21:36:02","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=20587"},"modified":"2020-06-01T21:36:07","modified_gmt":"2020-06-01T21:36:07","slug":"guinee-covid-19-la-situation-dans-le-pays-ce-lundi-anss","status":"publish","type":"post","link":"https:\/\/www.friaguinee.net\/index.php\/2020\/06\/01\/guinee-covid-19-la-situation-dans-le-pays-ce-lundi-anss\/","title":{"rendered":"Guin\u00e9e\/Covid-19: la situation dans le pays ce lundi (ANSS)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dimanche 31 mais (615) \u00e9chantillons ont \u00e9t\u00e9 test\u00e9s dont (73) positifs soit un indice de positivit\u00e9 de (12%).<br>\nDepuis le d\u00e9but de la maladie nous avons enregistr\u00e9s un total de (3 844) cas confirm\u00e9s. Pour cette journ\u00e9e (23) nouvelles gu\u00e9rissons ont \u00e9t\u00e9 enregistr\u00e9es pour un cumul de (2 135) et (18) personnes sont en r\u00e9animation dont (11) sous soins intensifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actuellement (714) patients sont hospitalis\u00e9s sur les diff\u00e9rents sites.<br>\nL\u2019un de nos piliers dans la lutte contre la COVID-19 est l\u2019investigation autour des cas suspects et contacts dans les familles, communaut\u00e9s et lieux de travail.<br>\nL\u2019investigation est une strat\u00e9gie visant \u00e0 rechercher activement les cas confirm\u00e9s, suspects et l\u2019ensemble des personnes ayant \u00e9t\u00e9 en contacts avec un cas confirm\u00e9 au sein de la communaut\u00e9. Ce qui concours \u00e0 limiter la chaine de propagation en identifiant les nouveaux cas et briser la chaine de transmission de la maladie.<br>\n Ce processus se fait \u00e0 diff\u00e9rents niveaux :<br>\n\u2663 Familial, les \u00e9quipes d\u2019investigation se rendent dans les familles des cas confirm\u00e9s pour identifier tous les membres de la famille vivant avec le cas confirm\u00e9 ou ayant eu un contact \u00e9troit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2663 Lieux de travail, lorsqu\u2019un cas est confirm\u00e9 dans un lieu de travail, il faut identifier toutes les personnes ayant \u00e9t\u00e9 en contact avec la personne confirm\u00e9e positive \u00e0 la COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2663 Formation sanitaire, elle consiste \u00e0 retracer l\u2019itin\u00e9raire du cas confirm\u00e9 \u00e0 partir des formations sanitaires qu\u2019il a ant\u00e9rieurement fr\u00e9quent\u00e9es.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2663 Communautaire, les \u00e9quipes d\u2019investigation en concert avec la communaut\u00e9 proc\u00e8dent \u00e0 une enqu\u00eate minutieuse pour identifier les personnes pr\u00e9sentant les signes \u00e9vocateurs de la COVID ou ayant \u00e9t\u00e9 en contact avec un cas confirm\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et enfin, les personnes identifi\u00e9es \u00e0 risque sont dites contact et suivies par nos \u00e9quipes sp\u00e9cialis\u00e9es pendant au moins 14 jours. <br>\nCe travail est r\u00e9alis\u00e9 quotidiennement par des agents, recrut\u00e9s et d\u00e9ploy\u00e9s en appui aux directions communales de la sant\u00e9 de Conakry et des directions pr\u00e9fectorales \u00e0 l\u2019int\u00e9rieur du pays.<br>\nAu cours de cet exercice, les \u00e9quipes d\u2019investigation font des s\u00e9ances de sensibilisation et apportent un soutien aux cas confirm\u00e9s et \u00e0 l\u2019ensemble des contacts.<br>\nCe dispositif permet de circonscrire tr\u00e8s rapidement les foyers de la pand\u00e9mie COVID-19 en vue de rompre sa chaine de contamination. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9ussite de cette strat\u00e9gie exige la participation et la responsabilit\u00e9 de chacun et de tous. Cela suppose que vous coop\u00e9rez avec les \u00e9quipes d\u2019investigation pour plus r\u00e9sultats. C\u2019est l\u2019occasion de remercier ceux et celles qui ont ouvert leurs portes pour nos diff\u00e9rentes \u00e9quipes d\u2019investigation et lan\u00e7ons un appel aux autres de bien vouloir faire comme ces familles et entreprises. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre responsabilit\u00e9 commune est engag\u00e9e face \u00e0 cette \u00e9pid\u00e9mie. <br>\nNous vous invitons \u00e0 pratiquer ces gestes simples que sont : <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Se laver correctement et syst\u00e9matiquement les mains \u00e0 l\u2019eau et au savon ou le gel hydro alcoolique ;<\/li><li>Porter correctement les masques devant toute autre personne <\/li><li>Respecter la distanciation physique d\u2019au moins 1m ;  <\/li><li>Limiter les d\u00e9placements au strict n\u00e9cessaire.<\/li><li>Notre responsabilit\u00e9 individuelle et collective est indispensable pour venir \u00e0 bout de cette \u00e9pid\u00e9mie.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dimanche 31 mais (615) \u00e9chantillons ont \u00e9t\u00e9 test\u00e9s dont (73) positifs soit un indice de positivit\u00e9 de (12%). Depuis le d\u00e9but de la maladie nous avons enregistr\u00e9s un total de (3 844) cas confirm\u00e9s. Pour cette journ\u00e9e (23) nouvelles gu\u00e9rissons ont \u00e9t\u00e9 enregistr\u00e9es pour un cumul de (2 135) et (18) personnes sont en r\u00e9animation [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20588,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[2582,148,907],"class_list":["post-20587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante","tag-covid-19","tag-guinee","tag-situation"],"_links":{"self":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/20587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=20587"}],"version-history":[{"count":1,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/20587\/revisions"}],"predecessor-version":[{"id":20589,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/20587\/revisions\/20589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/20588"}],"wp:attachment":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=20587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=20587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=20587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}