{"id":14700,"date":"2020-02-21T19:00:09","date_gmt":"2020-02-21T19:00:09","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=14700"},"modified":"2020-02-21T19:00:14","modified_gmt":"2020-02-21T19:00:14","slug":"football-antonio-souare-officiellement-installe-a-la-tete-de-lufoa-zone-a","status":"publish","type":"post","link":"https:\/\/www.friaguinee.net\/index.php\/2020\/02\/21\/football-antonio-souare-officiellement-installe-a-la-tete-de-lufoa-zone-a\/","title":{"rendered":"Football: Antonio Souar\u00e9 officiellement install\u00e9 \u00e0 la t\u00eate de L&rsquo;UFOA Zone A"},"content":{"rendered":"\n<p>Pr\u00e9sident de la Zone A de l\u2019UFOA depuis le 12 Octobre 2019, \u00e0 l\u2019issu d\u2019un vote, Mamadou Antonio Souar\u00e9, pr\u00e9sident de la Feguifoot a pris fonction ce vendredi 21 f\u00e9vrier 2020 \u00e0 Dakar. <\/p>\n\n\n\n<p>Le pr\u00e9sident de la f\u00e9d\u00e9ration s\u00e9n\u00e9galaise de football, Ma\u00eetre Augustin SENGHOR, pr\u00e9sident sortant a pass\u00e9 le t\u00e9moin au guin\u00e9en, lors d\u2019une c\u00e9r\u00e9monie de passation de service, organis\u00e9e \u00e0 cet effet dans la capitale s\u00e9n\u00e9galaise.<\/p>\n\n\n\n<p>Pendant les quatre prochaines ann\u00e9es, 2020 \u2013 2023, Antonio SOUAR\u00c9, pr\u00e9sident de la Feguifoot dirigera cette instance, l\u2019UFOA (union des f\u00e9d\u00e9rations Ouest africaines de football, zone A).<\/p>\n\n\n\n<p><strong>Ibrahima Sory Camara pour friaguinee.net <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9sident de la Zone A de l\u2019UFOA depuis le 12 Octobre 2019, \u00e0 l\u2019issu d\u2019un vote, Mamadou Antonio Souar\u00e9, pr\u00e9sident de la Feguifoot a pris fonction ce vendredi 21 f\u00e9vrier 2020 \u00e0 Dakar. Le pr\u00e9sident de la f\u00e9d\u00e9ration s\u00e9n\u00e9galaise de football, Ma\u00eetre Augustin SENGHOR, pr\u00e9sident sortant a pass\u00e9 le t\u00e9moin au guin\u00e9en, lors d\u2019une c\u00e9r\u00e9monie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14702,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[2009,2011,1838,2008,2010],"class_list":["post-14700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-antonio-souare","tag-officielle","tag-presidence","tag-ufoa","tag-zone-a"],"_links":{"self":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/14700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=14700"}],"version-history":[{"count":2,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/14700\/revisions"}],"predecessor-version":[{"id":14703,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/14700\/revisions\/14703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/14702"}],"wp:attachment":[{"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=14700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=14700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=14700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}