{"id":6423,"count":1,"description":"","link":"http:\/\/www.friaguinee.net\/index.php\/tag\/discours-kassory\/","name":"Discours Kassory","slug":"discours-kassory","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags\/6423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts?tags=6423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}