{"id":91714,"date":"2025-08-31T15:44:34","date_gmt":"2025-08-31T15:44:34","guid":{"rendered":"https:\/\/www.friaguinee.net\/?p=91714"},"modified":"2025-08-31T15:53:06","modified_gmt":"2025-08-31T15:53:06","slug":"referendum-constitutionnel-du-21-septembre-2025-le-premier-ministre-amadou-oury-bah-exhorte-la-population-a-voter-le-oui","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2025\/08\/31\/referendum-constitutionnel-du-21-septembre-2025-le-premier-ministre-amadou-oury-bah-exhorte-la-population-a-voter-le-oui\/","title":{"rendered":"Referendum constitutionnel du 21 septembre 2025 : appel du Premier ministre Amadou Oury Bah \u00e0 la mobilisation pour le \u00ab\u00a0OUI\u00a0\u00bb"},"content":{"rendered":"\n<p><strong>Chers compatriotes,<\/strong><\/p>\n\n\n\n<p><strong>\u00c0 l\u2019aube d\u2019un moment historique, nous nous adressons \u00e0 vous avec espoir.<\/strong><\/p>\n\n\n\n<p><strong>Le dimanche 21 septembre, nous aurons rendez-vous avec notre destin. Ce jour-l\u00e0,<\/strong><\/p>\n\n\n\n<p><strong>chacune et chacun d\u2019entre nous pourra, avec responsabilit\u00e9 et fiert\u00e9, \u00e9crire une<\/strong><\/p>\n\n\n\n<p><strong>nouvelle page de notre histoire commune.<\/strong><\/p>\n\n\n\n<p>Le projet de Constitution qui nous est propos\u00e9 est le fruit de nos combats, de nos<\/p>\n\n\n\n<p>aspirations profondes, et de notre volont\u00e9 collective de b\u00e2tir une R\u00e9publique plus<\/p>\n\n\n\n<p>juste, plus d\u00e9mocratique et plus solidaire.<\/p>\n\n\n\n<p>Ce texte consacre l\u2019\u00c9tat de droit, renforce les libert\u00e9s fondamentales, et ouvre des<\/p>\n\n\n\n<p>perspectives nouvelles pour la stabilit\u00e9 et le d\u00e9veloppement de notre Guin\u00e9e.<\/p>\n\n\n\n<p>Comme en 1958, nous avons aujourd\u2019hui l\u2019opportunit\u00e9 de tourner la page des<\/p>\n\n\n\n<p>incertitudes, pour en ouvrir une autre, marqu\u00e9e par l\u2019unit\u00e9, la r\u00e9conciliation et la<\/p>\n\n\n\n<p>confiance en notre avenir.<\/p>\n\n\n\n<p>Durant plusieurs semaines, ce projet a \u00e9t\u00e9 expliqu\u00e9, partag\u00e9, d\u00e9battu dans nos<\/p>\n\n\n\n<p>villes, nos campagnes, nos ambassades et consulats. Vous avez eu le temps de<\/p>\n\n\n\n<p>vous l\u2019approprier. Le temps est venu de le soumettre \u00e0 votre approbation.<\/p>\n\n\n\n<p>Le Gouvernement vous invite \u00e0 faire de ce vote un moment massif et historique.<\/p>\n\n\n\n<p>D\u00e8s demain, nous irons de nouveau \u00e0 votre rencontre. Nous dialoguerons, nous<\/p>\n\n\n\n<p>confronterons nos id\u00e9es, toujours dans le respect r\u00e9publicain.<\/p>\n\n\n\n<p>Et le 21 septembre, nous vous invitons, partout en Guin\u00e9e et dans la diaspora, \u00e0<\/p>\n\n\n\n<p>vous mobiliser pour le Oui.<\/p>\n\n\n\n<p>Ce Oui, n\u2019est pas celui d\u2019un camp contre un autre. C\u2019est celui de la Guin\u00e9e unie<\/p>\n\n\n\n<p>et debout, choisissant la voie de la stabilit\u00e9, du progr\u00e8s et de la dignit\u00e9 retrouv\u00e9e.<\/p>\n\n\n\n<p>C\u2019est un Oui pour la paix, un Oui pour des institutions modernes, un Oui pour<\/p>\n\n\n\n<p>transmettre un h\u00e9ritage solide aux g\u00e9n\u00e9rations futures.<\/p>\n\n\n\n<p>Faisons de ce r\u00e9f\u00e9rendum l\u2019expression vivante de notre d\u00e9mocratie et de notre<\/p>\n\n\n\n<p>volont\u00e9 commune de forger notre destin collectif.<\/p>\n\n\n\n<p>Ensemble, portons ce message d\u2019unit\u00e9, de renouveau et de Coh\u00e9sion.<\/p>\n\n\n\n<p><strong>Ensemble, faisons triompher la Guin\u00e9e.<\/strong><\/p>\n\n\n\n<p><strong>Vive la R\u00e9publique, vive la Refondation, vive la Guin\u00e9e ! \u00bb<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chers compatriotes, \u00c0 l\u2019aube d\u2019un moment historique, nous nous adressons \u00e0 vous avec espoir. Le dimanche 21 septembre, nous aurons rendez-vous avec notre destin. Ce jour-l\u00e0, chacune et chacun d\u2019entre nous pourra, avec responsabilit\u00e9 et fiert\u00e9, \u00e9crire une nouvelle page de notre histoire commune. Le projet de Constitution qui nous est propos\u00e9 est le fruit [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":91719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-91714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/91714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=91714"}],"version-history":[{"count":3,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/91714\/revisions"}],"predecessor-version":[{"id":91721,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/91714\/revisions\/91721"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/91719"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=91714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=91714"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=91714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}