{"id":636,"date":"2017-12-29T17:09:27","date_gmt":"2017-12-29T16:09:27","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=636"},"modified":"2017-12-29T17:09:27","modified_gmt":"2017-12-29T16:09:27","slug":"feguifoot-liberation-de-morthon-blasco","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2017\/12\/29\/feguifoot-liberation-de-morthon-blasco\/","title":{"rendered":"Feguifoot\u00a0: Lib\u00e9ration de Morthon et Blasco"},"content":{"rendered":"<p>Apr\u00e8s quelques semaines de d\u00e9tention \u00e0 la maison centrale ,Ibrahima Blasco Barry et \u00a0Aboubacar Morthon Soumah ont \u00e9t\u00e9 lib\u00e9r\u00e9s ce Vendredi 29 D\u00e9cembre. Le secr\u00e9taire g\u00e9n\u00e9ral et le chef de d\u00e9partement des finances sont accus\u00e9s de d\u00e9tournement de vingt milliards gnf par Antonio Souar\u00e9, le pr\u00e9sident de la F\u00e9d\u00e9ration Guin\u00e9enne de Football.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-637\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/images-1.jpg\" alt=\"\" width=\"297\" height=\"170\" \/><\/p>\n<p>Selon nos sources, les deux auraient pay\u00e9 chacun cent millions de nos francs pour recouvrer leur libert\u00e9 en attendant leur proc\u00e8s.<\/p>\n<p>A signaler que Salifou Super V Camara l\u2019ancien pr\u00e9sident de la Feguifoot, fait partie des accus\u00e9s mais, lui aurait quitt\u00e9 le pays depuis le d\u00e9clenchement de cette affaire.<\/p>\n<p>Abdoulaye Osvaldo Sylla<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-602 alignleft\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/14199566_1765491453732233_6388357177131054636_n-298x300.jpg\" alt=\"\" width=\"70\" height=\"71\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/14199566_1765491453732233_6388357177131054636_n-298x300.jpg 298w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/14199566_1765491453732233_6388357177131054636_n-150x150.jpg 150w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/14199566_1765491453732233_6388357177131054636_n-768x773.jpg 768w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/14199566_1765491453732233_6388357177131054636_n-356x364.jpg 356w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/14199566_1765491453732233_6388357177131054636_n-696x700.jpg 696w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/14199566_1765491453732233_6388357177131054636_n-417x420.jpg 417w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2017\/12\/14199566_1765491453732233_6388357177131054636_n.jpg 954w\" sizes=\"auto, (max-width: 70px) 100vw, 70px\" \/><\/p>\n<p>Tel:626 27 82 62<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s quelques semaines de d\u00e9tention \u00e0 la maison centrale ,Ibrahima Blasco Barry et \u00a0Aboubacar Morthon Soumah ont \u00e9t\u00e9 lib\u00e9r\u00e9s ce Vendredi 29 D\u00e9cembre. Le secr\u00e9taire g\u00e9n\u00e9ral et le chef de d\u00e9partement des finances sont accus\u00e9s de d\u00e9tournement de vingt milliards gnf par Antonio Souar\u00e9, le pr\u00e9sident de la F\u00e9d\u00e9ration Guin\u00e9enne de Football. Selon nos sources, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=636"}],"version-history":[{"count":0,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/638"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=636"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}