{"id":5914,"date":"2018-11-10T15:51:31","date_gmt":"2018-11-10T15:51:31","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=5914"},"modified":"2018-11-10T16:15:22","modified_gmt":"2018-11-10T16:15:22","slug":"fria-long-initiative-femme-de-guinee-renforce-les-capacites-de-100-femmes-en-entrepreneuriat-feminin","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2018\/11\/10\/fria-long-initiative-femme-de-guinee-renforce-les-capacites-de-100-femmes-en-entrepreneuriat-feminin\/","title":{"rendered":"Fria\u00a0: l\u2019ONG \u2018\u2019Initiative femme de Guin\u00e9e\u2019\u2019 renforce les capacit\u00e9s de 100 femmes en entrepreneuriat f\u00e9minin"},"content":{"rendered":"<p>C\u2019est dans une salle archi-comble que la d\u00e9l\u00e9gation de Mme Tour\u00e9 Fatoumata Camara a \u00e9t\u00e9 re\u00e7ue ce vendredi 9 novembre \u00e0 Fria.<\/p>\n<p>La pr\u00e9sence de la pr\u00e9sidente de l\u2019ONG Initiative femme de Guin\u00e9e s\u2019inscrit dans le cadre du lancement de la formation d\u2019une centaine de femmes sur le th\u00e8me \u2018\u2019entrepreneuriat agricole, une source d\u2019emploi pour les femmes\u2019\u2019.<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5915 alignleft\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/45730614_799991100332515_619422034560024576_n-1-300x169.jpg\" alt=\"\" width=\"275\" height=\"155\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/45730614_799991100332515_619422034560024576_n-1-300x169.jpg 300w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/45730614_799991100332515_619422034560024576_n-1.jpg 480w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/><\/p>\n<p>Dans son discours de bienvenu, le maire de la commune urbaine a remerci\u00e9 l\u2019ONG Initiative femme de Guin\u00e9e pour le choix port\u00e9 sur Fria quand on sait combien les femmes de Fria se sont battues pour g\u00e9rer la crise qui a min\u00e9 la cit\u00e9 pendant plus de cinq ans.<\/p>\n<p>Dans sa prise de parole, la pr\u00e9sidente de l\u2019ONG Initiative Femme de Guin\u00e9e, a dans la langue du terroir, expliqu\u00e9 le bien-fond\u00e9 de cette formation.<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5926 alignright\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/ifg.jpg\" alt=\"\" width=\"206\" height=\"206\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/ifg.jpg 280w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/ifg-150x150.jpg 150w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/p>\n<p>\u00ab\u00a0<em>Nous avons choisi Fria pour f\u00e9liciter et encourager les \u2018\u2019h\u00e9ro\u00efnes de la crise\u2019\u2019, nous savons que vous \u00eates capables, vous exercez des activit\u00e9s g\u00e9n\u00e9ratrices de revenus gr\u00e2ce auxquelles vous avez pu supporter vos familles lors de la crise. Ailleurs, toute personne qui exerce une activit\u00e9 \u00e0 son propre compte est appel\u00e9 auto-entrepreneur, nous savons que vous l\u2019\u00eates aussi, c\u2019est pourquoi nous avons d\u00e9cid\u00e9 de vous accompagner en renfor\u00e7ant vos capacit\u00e9s en entreprenariat agricole afin que vous vous tourniez aussi vers la terre. Il n\u2019est pas dit seulement qu\u2019un entrepreneur agricole c\u2019est celui qui prend la daba, l\u2019entreprenariat agricole est une chaine qui va du cultivateur au consommateur\u2026<\/em>\u00a0\u00bb a expliqu\u00e9 Mme Tour\u00e9 Fatoumata Camara.<\/p>\n<p>Organis\u00e9e en partenariat avec l\u2019ONG Alliance Fria, le repr\u00e9sentant de cette structure a pour sa part, exhorter les femmes de Fria \u00e0 accorder une attention particuli\u00e8re \u00e0 la formation.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5927 alignleft\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/nfaly.jpg\" alt=\"\" width=\"191\" height=\"191\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/nfaly.jpg 280w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/nfaly-150x150.jpg 150w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/>\u00ab\u00a0<em>Je vous invite femmes de Fria \u00e0 suivre attentivement cette formation afin qu\u2019elle vous soit b\u00e9n\u00e9fique. Si aujourd\u2019hui, cette formation s\u2019est tenue ici, c\u2019est gr\u00e2ce \u00e0 Aboubacar Makhissa Camara qui, lors d\u2019un atelier de formation \u00e0 l\u2019h\u00f4tel Sheraton de Conakry, a expliqu\u00e9 \u00e0 Mme Tour\u00e9 comment vous \u00eates d\u00e9vou\u00e9es. Nous souhaitons qu\u2019\u00e0 l\u2019issu de cette formation, que vous femmes de Fria, soyez en mesure de nous pr\u00e9senter des projets que nous soumettrons \u00e0 nos partenaires\u2026\u00a0<\/em>\u00bb a confi\u00e9 N\u2019Faly Tour\u00e9.<\/p>\n<p>Fatoumata Fama de la chambre pr\u00e9fectorale de l\u2019agriculture, n\u2019a pas manqu\u00e9 d\u2019exprimer au nom des femmes de Fria, toute sa reconnaissance \u00e0 l\u2019endroit des initiateurs de ce projet de formation.<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5909 alignright\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/entre-300x169.jpg\" alt=\"\" width=\"275\" height=\"155\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/entre-300x169.jpg 300w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/entre.jpg 480w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/><\/p>\n<p>\u00ab\u00a0<em>Qu\u2019on vous le dise ou pas, sachez que nous sommes ravies de votre acte, nous sommes fi\u00e8res de voir aujourd\u2019hui que ce sont nos enfants de Guin\u00e9e qui prennent de telles initiatives pour secourir les femmes. Nous vous remercions infiniment et promettons de suivre cette formation avec attention afin de pouvoir faire la restitution aux femmes qui ne sont pas l\u00e0 aujourd\u2019hui\u00a0<\/em>\u00bb a-t-elle d\u00e9clar\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5928 alignleft\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/art.jpg\" alt=\"\" width=\"199\" height=\"199\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/art.jpg 280w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2018\/11\/art-150x150.jpg 150w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/>Pour la premi\u00e8re journ\u00e9e, c\u2019est un panel de discussion et d\u2019\u00e9changes d\u2019exp\u00e9riences qui ont domin\u00e9. La deuxi\u00e8me et derni\u00e8re journ\u00e9e elle, a \u00e9t\u00e9 plus fructueuse \u00e0 travers les explications des diff\u00e9rentes techniques agricoles, donn\u00e9es par Monsieur Seydouba Bangoura, des \u00e9changes d&rsquo;exp\u00e9riences, des expositions d&rsquo;articles produits par les femmes et le tout a \u00e9t\u00e9 sanctionn\u00e9 par la remise d\u2019attestations aux b\u00e9n\u00e9ficiaires de la formation.<\/p>\n<p style=\"text-align: center;\"><strong>Dj\u00e9nabou Batco Diallo<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Tel: 628 28 67 44<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est dans une salle archi-comble que la d\u00e9l\u00e9gation de Mme Tour\u00e9 Fatoumata Camara a \u00e9t\u00e9 re\u00e7ue ce vendredi 9 novembre \u00e0 Fria. La pr\u00e9sence de la pr\u00e9sidente de l\u2019ONG Initiative femme de Guin\u00e9e s\u2019inscrit dans le cadre du lancement de la formation d\u2019une centaine de femmes sur le th\u00e8me \u2018\u2019entrepreneuriat agricole, une source d\u2019emploi pour [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[628,626,627,227,392,194,49,625],"class_list":["post-5914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publireportage","tag-agricole","tag-de-guinee","tag-entrepreneuriat","tag-femme","tag-femmes","tag-formation","tag-fria","tag-initiative"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/5914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=5914"}],"version-history":[{"count":6,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/5914\/revisions"}],"predecessor-version":[{"id":5929,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/5914\/revisions\/5929"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/5922"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=5914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=5914"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=5914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}