{"id":49169,"date":"2023-11-01T17:02:32","date_gmt":"2023-11-01T17:02:32","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=49169"},"modified":"2023-11-01T17:08:09","modified_gmt":"2023-11-01T17:08:09","slug":"fete-de-larmee-a-fria-cette-annee-est-une-annee-developpement-cdt-amadou-bah","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2023\/11\/01\/fete-de-larmee-a-fria-cette-annee-est-une-annee-developpement-cdt-amadou-bah\/","title":{"rendered":"F\u00eate de l\u2019arm\u00e9e \u00e0 Fria : \u00ab\u00a0Cette ann\u00e9e est une ann\u00e9e de d\u00e9veloppement\u00a0\u00bb (Cdt Amadou Bah)"},"content":{"rendered":"\n<p>A l\u2019instar des camps militaires de Conakry et des autres r\u00e9gions et pr\u00e9fectures de la Guin\u00e9e, les hommes en tenue de Fria ont c\u00e9l\u00e9br\u00e9 ce mercredi 1er Novembre 2023, le 65\u00e8me anniversaire de la cr\u00e9ation de l\u2019arm\u00e9e Guin\u00e9enne dans la plus grande sobri\u00e9t\u00e9 dans l\u2019enceinte du camp d\u2019infanterie de la pr\u00e9fecture de Fria en pr\u00e9sence des autorit\u00e9s pr\u00e9fectorales, communales, des sages et des citoyens civiles venus se joindre aux forces arm\u00e9es pour la circonstance.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/received_2447544685503952-1024x768-1.jpeg\" alt=\"\" class=\"wp-image-49170\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/received_2447544685503952-1024x768-1.jpeg 1024w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/received_2447544685503952-1024x768-1-300x225.jpeg 300w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/received_2447544685503952-1024x768-1-768x576.jpeg 768w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/received_2447544685503952-1024x768-1-80x60.jpeg 80w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/received_2447544685503952-1024x768-1-265x198.jpeg 265w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/received_2447544685503952-1024x768-1-696x522.jpeg 696w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/received_2447544685503952-1024x768-1-560x420.jpeg 560w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A l\u2019entame de la c\u00e9r\u00e9monie protocolaire militaire, le colonel Amadou Bah,commandant de la compagnie d\u2019infanterie militaire, apr\u00e8s la prise d\u2019armes, a demand\u00e9 \u00e0 ses h\u00f4tes civiles et militaires venus c\u00e9l\u00e9brer cette f\u00eate d\u2019observer une minute de silence en la m\u00e9moire des devanciers qui sont tomb\u00e9s l\u2019arme \u00e0 la main.<\/p>\n\n\n\n<p>Dans son discours de bienvenue, le colonel Amadou Bah commandant de la compagnie d\u2019infanterie de Fria est revenu sur la bravoure des hommes en tenue et leur implication dans le r\u00e9tablissement de la paix dans les pays voisins.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"744\" height=\"850\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/367396204_655952723272787_1044654673708656470_n.jpg\" alt=\"\" class=\"wp-image-49171\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/367396204_655952723272787_1044654673708656470_n.jpg 744w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/367396204_655952723272787_1044654673708656470_n-263x300.jpg 263w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/367396204_655952723272787_1044654673708656470_n-696x795.jpg 696w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/367396204_655952723272787_1044654673708656470_n-368x420.jpg 368w\" sizes=\"auto, (max-width: 744px) 100vw, 744px\" \/><figcaption>                          <strong>Colonel AMADOU BAH Commandant d&rsquo;infanterie de Fria<\/strong><\/figcaption><\/figure>\n\n\n\n<p>&nbsp;\u00ab <strong><em>A l\u2019occasion du 65\u00e8me anniversaire de notre vaillante arm\u00e9e, les forces de d\u00e9fense et de s\u00e9curit\u00e9 de Fria par ma voix vous souhaitent la bienvenue dans l\u2019enceint de notre camp pour comm\u00e9morer ensemble cette journ\u00e9e inoubliable. Cette arm\u00e9e dont nous comm\u00e9morons le 65\u00e8me anniversaire est depuis sa cr\u00e9ation par nos devanciers tels que : NOUMANDIAN KEITA, KAMAN DIABY pour ne citer que ceux-ci, qui ont renonc\u00e9 les avantages que les colons les ont propos\u00e9 pour r\u00e9pondre \u00e0 l\u2019appel patriotique le 1 er Novembre 1958<\/em><\/strong>\u00bb a d\u00e9clar\u00e9 le colonel Amadou Bah.<\/p>\n\n\n\n<p>Poursuivant le colonel a rappel\u00e9 la loyaut\u00e9 de l\u2019arm\u00e9e Guin\u00e9enne pendant tous les r\u00e9gimes qui se sont succ\u00e8d\u00e9s<br>\u00ab <strong><em>Depuis cette date jusqu&rsquo;\u00e0 aujourd&rsquo;hui, elle a fait preuve de bravoure et de capacit\u00e9s sur tous les fronts. Elle a aid\u00e9 beaucoup de pays africains \u00e0 retrouver leurs souverainet\u00e9s comme par exemple: la Guin\u00e9e Bissau, le Mozambique, l\u2019Angola.&nbsp; Par cons\u00e9quent,tous les&nbsp; chefs d&rsquo;\u00c9tat qui se sont succ\u00e9d\u00e9 dans notre pays, l\u2019arm\u00e9e a \u00e9t\u00e9 tr\u00e8s loyale avec eux. Aujourd\u2019hui l\u2019arm\u00e9e a renou\u00e9 avec sa population, elle est sur tous les fronts, elle participe activement aux actions civilo-militaires. qui sont quotidiennement sur le terrain, elle lutte contre l\u2019autosuffisance alimentaire \u00e0 travers les journ\u00e9es agricoles, la construction des infrastructures par le g\u00e9nie militaire, elle \u00e9volue dans beaucoup de missions onusiennes telles que le Mali, la MINUSMA, l\u2019arm\u00e9e est toujours fid\u00e8le \u00e0 sa mission r\u00e9galienne. Pour terminer permettez-moi de rendre un vibrant hommage au pr\u00e9sident Colonel MAMADI DOUMBOUYA, commandant en chef des Forces Arm\u00e9es qui n\u2019a m\u00e9nag\u00e9 aucun effort pour la stabilisation de la paix en Guin\u00e9e<\/em><\/strong> \u00bb a ajout\u00e9 le commandant.<\/p>\n\n\n\n<p>Pour sa part le colonel Alpha Oumar Ciss\u00e9 pr\u00e9fet de Fria pr\u00e9sent \u00e0 cette c\u00e9r\u00e9monie, a souhait\u00e9 une bonne f\u00eate aux hommes en tenue de l\u2019arm\u00e9e et \u00e0 tous les civils qui sont les amis et fr\u00e8res des Forces de d\u00e9fense et de s\u00e9curit\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"755\" height=\"666\" src=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/395943438_874188100889655_4673417218897630309_n.jpg\" alt=\"\" class=\"wp-image-49172\" srcset=\"http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/395943438_874188100889655_4673417218897630309_n.jpg 755w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/395943438_874188100889655_4673417218897630309_n-300x265.jpg 300w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/395943438_874188100889655_4673417218897630309_n-696x614.jpg 696w, http:\/\/www.friaguinee.net\/wp-content\/uploads\/2023\/11\/395943438_874188100889655_4673417218897630309_n-476x420.jpg 476w\" sizes=\"auto, (max-width: 755px) 100vw, 755px\" \/><figcaption>                                       <strong>Colonel ALPHA OUMAR CISSE pr\u00e9fet de Fria<\/strong><\/figcaption><\/figure>\n\n\n\n<p>&nbsp;\u00ab <strong><em>Permettez-moi au nom de toutes les autorit\u00e9s \u00e0 tous les niveaux et \u00e0 mon nom personnel de vous souhaiter bonne f\u00eate. Bonne f\u00eate \u00e0 tous les compagnons, bonne f\u00eate aux autorit\u00e9s, bonne f\u00eate aux services de d\u00e9fense et de s\u00e9curit\u00e9 qui ne m\u00e9nagent aucun effort pour que cette relation civilo-militaire soit une r\u00e9alit\u00e9 en R\u00e9publique de Guin\u00e9e. Merci au pr\u00e9sident de la r\u00e9publique chef de l\u2019\u00c9tat, chef supr\u00eame des Forces Arm\u00e9es guin\u00e9ennes le colonel MAMADI DOUMBOUYA qui, avec sa vision patriotique ne m\u00e9nage aucun effort pour que l\u2019arm\u00e9e Guin\u00e9enne connaisse le bonheur. Et aujourd\u2019hui sans en abuser, les multiples missions de d\u00e9veloppement de l\u2019arm\u00e9e guin\u00e9enne sont visibles <\/em><\/strong>\u00bb a-t-il affirm\u00e9.<\/p>\n\n\n\n<p>C\u2019est apr\u00e8s les b\u00e9n\u00e9dictions des sages que la c\u00e9r\u00e9monie a pris fin autour des plats copieux dans une ambiance de f\u00eate<\/p>\n\n\n\n<p><strong>Alhassane Mayenie Camara<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l\u2019instar des camps militaires de Conakry et des autres r\u00e9gions et pr\u00e9fectures de la Guin\u00e9e, les hommes en tenue de Fria ont c\u00e9l\u00e9br\u00e9 ce mercredi 1er Novembre 2023, le 65\u00e8me anniversaire de la cr\u00e9ation de l\u2019arm\u00e9e Guin\u00e9enne dans la plus grande sobri\u00e9t\u00e9 dans l\u2019enceinte du camp d\u2019infanterie de la pr\u00e9fecture de Fria en pr\u00e9sence [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":49171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-49169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/49169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=49169"}],"version-history":[{"count":2,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/49169\/revisions"}],"predecessor-version":[{"id":49176,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/49169\/revisions\/49176"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/49171"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=49169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=49169"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=49169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}