{"id":46077,"date":"2022-10-26T20:12:23","date_gmt":"2022-10-26T20:12:23","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=46077"},"modified":"2022-10-26T20:12:26","modified_gmt":"2022-10-26T20:12:26","slug":"guillaum-hawing-a-fria-le-dpe-toure-abdoul-karim-promet-de-relever-le-defi-aux-differents-examens-de-fin-dannee-2022-2023","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2022\/10\/26\/guillaum-hawing-a-fria-le-dpe-toure-abdoul-karim-promet-de-relever-le-defi-aux-differents-examens-de-fin-dannee-2022-2023\/","title":{"rendered":"Guillaum Hawing \u00e0 Fria : le DPE Tour\u00e9 Abdoul Karim\u00a0promet de relever le d\u00e9fi aux diff\u00e9rents examens de fin d\u2019ann\u00e9e 2022-2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Guillaum Hawing ministre de l\u2019enseignement pr\u00e9-universitaire et de l\u2019Alphab\u00e9tisation  s&rsquo;est rendu ce mercredi 26 octobre 2022 \u00e0 Fria dans le but de s&rsquo;enqu\u00e9rir du niveau d\u2019avancement des travaux de r\u00e9novation du coll\u00e8ge Hadja M\u2019Mah<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tour\u00e9 Abdoul Karim Directeur Pr\u00e9fectoral de l\u2019Education de Fria revient sur les objectifs de\u00a0la visite du ministre Guillaume hawing dans la cit\u00e9 de l&rsquo;albumine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSon excellence Guillaume Hawing \u00e9tait \u00e0 Fria pour deux objectifs; le premier \u00e9tait de venir s\u2019enqu\u00e9rir du niveau d\u2019avancement de la r\u00e9novation du coll\u00e8ge Hadja M\u2019Mah Camara et de toucher du doigt les r\u00e9alit\u00e9s de la rentr\u00e9e des classe dans cette \u00e9cole en pleine r\u00e9novation, le deuxi\u00e8me but c\u2019\u00e9tait de voir effectivement est-ce que la formation des enseignants du CP1 a r\u00e9ellement d\u00e9marr\u00e9\u00a0\u00bb a rappel\u00e9 le DPE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">poursuivant le DPE se dit&nbsp; tr\u00e8s satisfait des constats du ministre<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c L&rsquo;arriv\u00e9e de la premi\u00e8re autorit\u00e9 sur le plan \u00e9ducatif dans ma pr\u00e9fecture est un sentiment de joie et de satisfaction. Je profite de cette occasion pour remercier la premi\u00e8re autorit\u00e9 de Fria, le colonel Alpha Oumar Ciss\u00e9 qui a pris tout son temps pour nous accompagner depuis hier jusqu\u2019\u00e0 maintenant. Ce que je peux retenir du ministre, se sont ses conseils qu\u2019il nous a prodigu\u00e9 notamment de relever le d\u00e9fi par rapport aux \u00e9checs de l\u2019ann\u00e9e pass\u00e9e, car nous avons \u00e9t\u00e9 \u00e0 l\u2019IRE de Bok\u00e9 pour signer un contrat de performance et ce contrat sera sign\u00e9 \u00e0 tous les niveaux, tout un chacun sera suivi donc il y a un r\u00e9sultat qui nous attend.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plus loin le DPE dit s\u2019attendre \u00e0 un taux de r\u00e9ussite plus \u00e9lev\u00e9 des enfants par rapport \u00e0 l\u2019ann\u00e9e derni\u00e8re<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c Je dirai \u00e0 l&rsquo;ensemble de ces cadres&nbsp; que le r\u00e9sultat que j\u2019attend, c\u2019est la r\u00e9ussite des enfants au niveau des diff\u00e9rents examens, c\u2019est le premier objectif du ministre d\u2019abord, il faudrait que le taux de r\u00e9ussite soit \u00e9lev\u00e9 par rapport \u00e0 l\u2019ann\u00e9e pass\u00e9e\u201d ajoute-t-il<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cet effet le DPE lance un appel \u00e0 tous les niveaux&nbsp; pour escompter avoir de bons r\u00e9sultats aux diff\u00e9rents examens de cette ann\u00e9e<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c Je commencerai d\u2019abord par les parents d\u2019\u00e9l\u00e8ves, les parents d\u2019\u00e9l\u00e8ves doivent avoir un bon suivi au niveau des enfants et de dire aussi aux \u00e9l\u00e8ves une fois \u00e0 l\u2019\u00e9cole, d\u2019\u00eatre assidus, ponctuels et une fois \u00e0 la maison de reprendre les exercices et les devoirs\u201d conclut-il<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A rappeler que le DPE ne fait pasque le bureaucrate, de temps en temps dispense des cours de chimie de la dixi\u00e8me en terminale et dans les lyc\u00e9e, les sciences&nbsp; math\u00e9matique et les sciences exp\u00e9rimentales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sal\u00e9matou Bald\u00e9<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guillaum Hawing ministre de l\u2019enseignement pr\u00e9-universitaire et de l\u2019Alphab\u00e9tisation s&rsquo;est rendu ce mercredi 26 octobre 2022 \u00e0 Fria dans le but de s&rsquo;enqu\u00e9rir du niveau d\u2019avancement des travaux de r\u00e9novation du coll\u00e8ge Hadja M\u2019Mah Tour\u00e9 Abdoul Karim Directeur Pr\u00e9fectoral de l\u2019Education de Fria revient sur les objectifs de\u00a0la visite du ministre Guillaume hawing dans la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":46080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-46077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/46077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=46077"}],"version-history":[{"count":2,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/46077\/revisions"}],"predecessor-version":[{"id":46081,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/46077\/revisions\/46081"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/46080"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=46077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=46077"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=46077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}