{"id":45490,"date":"2022-09-16T09:54:37","date_gmt":"2022-09-16T09:54:37","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=45490"},"modified":"2022-09-16T09:54:39","modified_gmt":"2022-09-16T09:54:39","slug":"urgent-kankan-kouroussa-14-morts-dont-11-calcines-dans-un-grave-accident-de-circulation","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2022\/09\/16\/urgent-kankan-kouroussa-14-morts-dont-11-calcines-dans-un-grave-accident-de-circulation\/","title":{"rendered":"Urgent \u2013 Kankan\/Kouroussa : 14 morts dont 11 calcin\u00e9s dans un grave accident de circulation"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un grave accident de la circulation s\u2019est produit la nuit derni\u00e8re \u00e0 la sortie de la commune urbaine de Kouroussa sur la route nationale Kankan-Kouroussa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon une source \u00e0 la pr\u00e9fecture de ladite localit\u00e9, le bilan macabre fait \u00e9tat de 14 morts dont 11 calcin\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A noter que\u00a0pour l\u2019heure, les circonstances de cet accident ne sont pas encore connues.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous y reviendrons\u2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grave accident de la circulation s\u2019est produit la nuit derni\u00e8re \u00e0 la sortie de la commune urbaine de Kouroussa sur la route nationale Kankan-Kouroussa. Selon une source \u00e0 la pr\u00e9fecture de ladite localit\u00e9, le bilan macabre fait \u00e9tat de 14 morts dont 11 calcin\u00e9s. A noter que\u00a0pour l\u2019heure, les circonstances de cet accident ne [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-45490","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/45490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=45490"}],"version-history":[{"count":1,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/45490\/revisions"}],"predecessor-version":[{"id":45492,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/45490\/revisions\/45492"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/45491"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=45490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=45490"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=45490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}