{"id":38600,"date":"2021-09-23T15:24:52","date_gmt":"2021-09-23T15:24:52","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=38600"},"modified":"2021-09-23T23:43:17","modified_gmt":"2021-09-23T23:43:17","slug":"fria-ordre-dans-la-circulation-routiere-le-prefet-donne-un-ultimatum-aux-taxi-motards","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2021\/09\/23\/fria-ordre-dans-la-circulation-routiere-le-prefet-donne-un-ultimatum-aux-taxi-motards\/","title":{"rendered":"Fria\/Ordre dans la circulation routi\u00e8re : le Pr\u00e9fet donne un ultimatum aux taxi-motards"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans le cadre de sa prise de contact avec toutes les couches sociales de la pr\u00e9f\u00e9cture de Fria, le colonel Yaya Kalissa a conf\u00e9r\u00e9 ce jeudi 23 septembre 2021 avec le syndicat des transporteurs routiers et taxis motos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette rencontre qui avait pour but d&rsquo;\u00e9changer en vue d&rsquo;une franche collaboration, a eu lieu dans la salle de r\u00e9union du bloc administratif, en pr\u00e9sence du secr\u00e9taire g\u00e9n\u00e9ral charg\u00e9 des affaires administratives, les repr\u00e9sentants du bureau des syndicats et la presse locale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Pr\u00e9fet lors de sa prise de parole a rappel\u00e9 aux syndicats des transporteurs routiers et taxis motos, les raisons de la prise du pouvoir par le C.N.R.D avant de leur tendre une main franche de collaboration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0<strong><em>Je m&rsquo;adresse \u00e0 vous au nom du CNRD et du Pr\u00e9sident Mamady Doumbouya pour vous expliquer les raisons fondamentales de la prise de pouvoir par le CNRD au nom du peuple de Guin\u00e9e. Nous devons ensemble travailler la main dans la main, parler le m\u00eame langage dans l&rsquo;ordre, la discipline, la compr\u00e9hension, le dialogue et la transparence. Pour cela moi je vous tends une main franche de collaboration, d&rsquo;entente. Les lois seront appliqu\u00e9es sachez que le syst\u00e8me a chang\u00e9 car tout est dissout. Faites un sacrifice pour soulager la population dans le cadre du transport. Je n&rsquo;impose rien mais faites un effort<\/em><\/strong>\u00a0\u00bb a exhort\u00e9 Colonel Yaya Kalissa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plus loin, le premier magistrat de la ville s&rsquo;est engag\u00e9 \u00e0 mettre de l&rsquo;ordre dans la circulation routi\u00e8re. Pour y parvenir, il a donn\u00e9 un ultimatum aux conducteurs de motos taxis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0<strong><em>Je demande au syndicat des taxis motos de mettre de l&rsquo;ordre dans la circulation. Je vous donne une semaine, avant le 02 octobre, je ne veux plus voir les motos gar\u00e9es sur les abords de la route. Il faut que la circulation soit lib\u00e9r\u00e9e. Je vous demande de nous accompagner pour non seulement  la r\u00e9ussite du CNRD mais aussi pour la s\u00e9curit\u00e9 des populations<\/em><\/strong>\u00ab\u00a0, a-t-il d\u00e9clar\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A son tour, le secr\u00e9taire g\u00e9n\u00e9ral du syndicat des transporteurs routiers a au nom de sa structure, r\u00e9it\u00e9r\u00e9 son engagement \u00e0 accompagner les nouvelles autorit\u00e9s du pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0<strong><em>Nous saluons le CNRD qui est venu nous lib\u00e9rer \u00e0 temps et au bon moment et nous sommes pr\u00eats \u00e0 vous accompagner pour le d\u00e9veloppement de notre pays plus particuli\u00e8rement la ville de Fria<\/em><\/strong>\u00ab\u00a0, a indiqu\u00e9 Moustapha Balbaky.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A noter que depuis sa prise de fonction, Colonel Yaya Kalissa a rencontr\u00e9 plusieurs acteurs de la vie socio-professionnelle de la localit\u00e9, notamment les sages.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Abdoulaye Barry pour friaguinee.net<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de sa prise de contact avec toutes les couches sociales de la pr\u00e9f\u00e9cture de Fria, le colonel Yaya Kalissa a conf\u00e9r\u00e9 ce jeudi 23 septembre 2021 avec le syndicat des transporteurs routiers et taxis motos. Cette rencontre qui avait pour but d&rsquo;\u00e9changer en vue d&rsquo;une franche collaboration, a eu lieu dans la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":38048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[49,84,3985,8058],"class_list":["post-38600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe","tag-fria","tag-prefet","tag-taxis-motos","tag-yaya-kalissa"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/38600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=38600"}],"version-history":[{"count":7,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/38600\/revisions"}],"predecessor-version":[{"id":38620,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/38600\/revisions\/38620"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/38048"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=38600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=38600"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=38600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}