{"id":37489,"date":"2021-08-18T17:16:07","date_gmt":"2021-08-18T17:16:07","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=37489"},"modified":"2021-08-18T17:16:08","modified_gmt":"2021-08-18T17:16:08","slug":"guinee-infrastructures-routieres-une-societe-prete-a-poser-du-bitume-a-moitie-prix","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2021\/08\/18\/guinee-infrastructures-routieres-une-societe-prete-a-poser-du-bitume-a-moitie-prix\/","title":{"rendered":"Guin\u00e9e\/Infrastructures routi\u00e8res : une soci\u00e9t\u00e9 pr\u00eate \u00e0 poser du bitume \u00e0 moiti\u00e9 prix"},"content":{"rendered":"\n<p>La soci\u00e9t\u00e9 allemande \u2018\u2019International Trading Group\u2019\u2019 est pr\u00eate \u00e0 poser le kilom\u00e8tre de bitume \u00e0&nbsp;cinq cent mille (500 000&nbsp;\u20ac). L\u2019annonce est faite ce mercredi au cours d&rsquo;une audience accord\u00e9e par le Premier ministre, Chef du Gouvernement.<\/p>\n\n\n\n<p><strong>Ralf Kramer,&nbsp;<\/strong>Pr\u00e9sident Directeur G\u00e9n\u00e9ral du groupe et sa d\u00e9l\u00e9gation sont introduits&nbsp;au palais de la Colombe par le ministre conseiller charg\u00e9 de mission&nbsp; Moussa Cond\u00e9 (Tata Vieux) et le conseiller de mission&nbsp;\u00e0 la pr\u00e9sidence Moalim&nbsp;Tour\u00e9.<\/p>\n\n\n\n<p>L\u2019investisseur allemand est&nbsp;pr\u00e9sent&nbsp;en Guin\u00e9e depuis six mois avec son groupe de gestion d&rsquo;engins lourds.&nbsp;Ralf Kramer&nbsp;a dit au Premier ministre son souhait d\u2019accompagner le Gouvernement dans le d\u00e9veloppement rapide et solide des infrastructures de transport et particuli\u00e8rement de routes. Sa promesse forte est de pouvoir \u00ab\u00a0construire des routes&nbsp;aux normes internationales en Guin\u00e9e&nbsp;\u00e0 petit co\u00fbt, c\u2019est-\u00e0-dire cinq cent mille (500 000&nbsp;\u20ac\/km)&nbsp;euros par kilom\u00e8tre au lieu d\u2019un million de dollars environ en ce moment\u00a0\u00bb. Mieux, le patron de l&rsquo;International Trading Group engage sa soci\u00e9t\u00e9 \u00e0 assurer&nbsp;gratuitement&nbsp;l&rsquo;entretien&nbsp; de la chauss\u00e9e pendant 10 ans en rapport avec&nbsp;le Fond d\u2019Entretien Routier.&nbsp;<\/p>\n\n\n\n<p>Aid\u00e9&nbsp;d&rsquo;un traducteur guin\u00e9en,&nbsp;Ralf Kramer a expliqu\u00e9 qu&rsquo;il dispose d\u2019\u00e9quipements de pointe qui permettent de poser par jour 5 km de bitume sur une bande de 7m de large. Il s&rsquo;est montr\u00e9 choqu\u00e9 par la d\u00e9gradation rapide des infrastructures routi\u00e8res am\u00e9nag\u00e9es&nbsp; et la stagnation d&rsquo;eau sur la&nbsp;chauss\u00e9e.&nbsp;<\/p>\n\n\n\n<p>A court termes, l&rsquo;International Trading Group compte implanter des usines modernes de fabriques de bitume, ciment, b\u00e9ton et fabriques de pav\u00e9s. \u00ab\u00a0Il s&rsquo;agira d&rsquo;un investissement \u00e0 double sens tourn\u00e9 vers la cr\u00e9ation d\u2019emploi et la formation\u00a0\u00bb.<\/p>\n\n\n\n<p>Convaincu de la qualit\u00e9 de la technologie allemande,\u00a0le Premier ministre apporte son appui\u00a0\u00e0\u00a0la soci\u00e9t\u00e9\u00a0International Trading Group\u00a0mais\u00a0recommande aux promoteurs de travailler techniquement avec le minist\u00e8re des Travaux Publics pour\u00a0pr\u00e9senter\u00a0des propositions d\u2019\u00e9tudes de projets viables. \u00ab\u00a0Le Gouvernement recevra les r\u00e9sultats de la concertations et les conditions contractuelles\u00a0\u00bb a conclu Dr Kassory Fofana.<\/p>\n\n\n\n<p>PG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 allemande \u2018\u2019International Trading Group\u2019\u2019 est pr\u00eate \u00e0 poser le kilom\u00e8tre de bitume \u00e0&nbsp;cinq cent mille (500 000&nbsp;\u20ac). L\u2019annonce est faite ce mercredi au cours d&rsquo;une audience accord\u00e9e par le Premier ministre, Chef du Gouvernement. Ralf Kramer,&nbsp;Pr\u00e9sident Directeur G\u00e9n\u00e9ral du groupe et sa d\u00e9l\u00e9gation sont introduits&nbsp;au palais de la Colombe par le ministre conseiller [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":37491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3990],"tags":[7877,148,7874,1410,2110,7875,7876],"class_list":["post-37489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medias","tag-bitume","tag-guinee","tag-infrastructures-routieres","tag-kassory-fofana","tag-premier-ministre","tag-pro-mature","tag-societe-allemande"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/37489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=37489"}],"version-history":[{"count":1,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/37489\/revisions"}],"predecessor-version":[{"id":37490,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/37489\/revisions\/37490"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/37491"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=37489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=37489"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=37489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}