{"id":32604,"date":"2021-04-20T13:35:36","date_gmt":"2021-04-20T13:35:36","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=32604"},"modified":"2021-04-20T13:35:37","modified_gmt":"2021-04-20T13:35:37","slug":"tchad-un-conseil-militaire-dirige-par-son-fils-remplace-le-president-deby-decede-ce-mardi","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2021\/04\/20\/tchad-un-conseil-militaire-dirige-par-son-fils-remplace-le-president-deby-decede-ce-mardi\/","title":{"rendered":"Tchad : un conseil militaire dirig\u00e9 par son fils remplace le pr\u00e9sident D\u00e9by d\u00e9c\u00e9d\u00e9 ce mardi"},"content":{"rendered":"\n<p>Un de ses fils, g\u00e9n\u00e9ral quatre \u00e9toiles \u00e0 37 ans et commandant de la garde pr\u00e9sidentielle, Mahamat Idriss D\u00e9by Itno, dirige un conseil militaire charg\u00e9 de remplacer le pr\u00e9sident tchadien Idriss D\u00e9by Itno d\u00e9c\u00e9d\u00e9 mardi, a annonc\u00e9 l\u2019arm\u00e9e \u00e0 la radio d\u2019Etat.<\/p>\n\n\n\n<p>\u00ab&nbsp;Un conseil militaire a \u00e9t\u00e9 en mis en place dirig\u00e9 par son fils, le g\u00e9n\u00e9ral Mahamat Idriss D\u00e9by Itno&nbsp;\u00bb, a d\u00e9clar\u00e9 le porte-parole de l\u2019arm\u00e9e, le g\u00e9n\u00e9ral Azem Bermandoa Agouna, dans un communiqu\u00e9 lu \u00e0 l\u2019antenne de la Radio nationale, peu de temps apr\u00e8s qu\u2019il eut annonc\u00e9 la mort du chef de l\u2019Etat \u2013 \u00e0 peine r\u00e9\u00e9lu \u2013 dans des combats contre les rebelles dans le nord.<\/p>\n\n\n\n<p>\u00ab&nbsp;Le conseil s\u2019est aussit\u00f4t r\u00e9uni et a promulgu\u00e9 la charte de transition&nbsp;\u00bb, a-t-il ajout\u00e9.<\/p>\n\n\n\n<p>Le jeune g\u00e9n\u00e9ral de corps d\u2019arm\u00e9e Mahamat D\u00e9by apparaissait r\u00e9guli\u00e8rement, lunettes noires cachant son regard et en tenue de camouflage, aux c\u00f4t\u00e9s de son p\u00e8re dont il contr\u00f4lait personnellement la s\u00e9curit\u00e9 rapproch\u00e9e \u00e0 la t\u00eate de soldats de son unit\u00e9 d\u2019\u00e9lite aux b\u00e9rets rouges, la toute puissante Direction G\u00e9n\u00e9rale des Services de S\u00e9curit\u00e9 des Institutions de l\u2019Etat (DGSSIE), plus connue des Tchadiens sous le nom de Garde pr\u00e9sidentielle.<\/p>\n\n\n\n<p>L\u2019arm\u00e9e n\u2019a pas indiqu\u00e9 ce qu\u2019elle entendait par \u00ab&nbsp;charte de transition&nbsp;\u00bb.<\/p>\n\n\n\n<p>Le mar\u00e9chal D\u00e9by, au pouvoir sans partage depuis un coup d\u2019Etat en 1990, avait plac\u00e9 les hommes et femmes de sa famille, de son clan et de sa tribu des Zaghawas \u00e0 la t\u00eate des diff\u00e9rentes unit\u00e9s de l\u2019arm\u00e9e mais aussi des grandes institutions et des principaux rouages de l\u2019\u00e9conomie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un de ses fils, g\u00e9n\u00e9ral quatre \u00e9toiles \u00e0 37 ans et commandant de la garde pr\u00e9sidentielle, Mahamat Idriss D\u00e9by Itno, dirige un conseil militaire charg\u00e9 de remplacer le pr\u00e9sident tchadien Idriss D\u00e9by Itno d\u00e9c\u00e9d\u00e9 mardi, a annonc\u00e9 l\u2019arm\u00e9e \u00e0 la radio d\u2019Etat. \u00ab&nbsp;Un conseil militaire a \u00e9t\u00e9 en mis en place dirig\u00e9 par son fils, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[6768,6767,495,5293],"class_list":["post-32604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-afrique","tag-conseil-militaire","tag-deby","tag-fils","tag-tchad"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=32604"}],"version-history":[{"count":1,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32604\/revisions"}],"predecessor-version":[{"id":32606,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32604\/revisions\/32606"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/32605"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=32604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=32604"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=32604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}