{"id":32422,"date":"2021-04-17T10:02:31","date_gmt":"2021-04-17T10:02:31","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=32422"},"modified":"2021-04-17T10:02:34","modified_gmt":"2021-04-17T10:02:34","slug":"feguifoot-retour-sur-le-deal-qui-pourrait-couter-les-yeux-de-la-tete-a-antonio-et-etre-une-victoire-qui-en-mettrait-la-main-au-feu-pour-kpc","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2021\/04\/17\/feguifoot-retour-sur-le-deal-qui-pourrait-couter-les-yeux-de-la-tete-a-antonio-et-etre-une-victoire-qui-en-mettrait-la-main-au-feu-pour-kpc\/","title":{"rendered":"FEGUIFOOT : Retour sur le deal qui pourrait co\u00fbter les yeux de la t\u00eate \u00e0 Antonio et \u00eatre une victoire qui en mettrait la main au feu pour KPC"},"content":{"rendered":"\n<p>\u00a0<a href=\"whatsapp:\/\/send?text=FEGUIFOOT+%3A+Retour+sur+le+deal+qui+pourrait+co%C3%BBter+les+yeux+de+la+t%C3%AAte+%C3%A0+Antonio+et+%C3%AAtre+une+victoire+qui+en+mettrait+la+main+au+feu+pour+KPC+%28%C5%92il+d%E2%80%99un+observateur%29 %0A%0A https:\/\/kibaro224.com\/feguifoot-retour-sur-le-deal-qui-pourrait-couter-les-yeux-de-la-tete-a-antonio-et-etre-une-victoire-qui-en-mettrait-la-main-au-feu-pour-kpc-oeil-dun-observateur\/\"><\/a>La course entre Antonio et KPC \u00e0 la Pr\u00e9sidence de la F\u00e9d\u00e9ration Guin\u00e9enne de Football (FEGUIFOOT), n\u2019aura \u00e9t\u00e9 qu\u2019un bide au bout du compte. Pourtant, la bataille \u00e9tait bien partie et semblait livrer des sc\u00e9narios \u00e0 l\u2019image d\u2019une s\u00e9rie Am\u00e9ricaine. De part et d\u2019autre, les \u00e9pisodes pr\u00e9sent\u00e9s \u00e9taient de tout feu tout flamme. Mais finalement, tout n\u2019aura \u00e9t\u00e9 que du vacarme pour juste nous casser les oreilles. Antonio et KPC ont fini par s\u2019entendre autour de quelque chose ou du moins trouver un compromis am\u00e8re. Que s\u2019est-il pass\u00e9 r\u00e9ellement ? KPC a-t-il baiss\u00e9 les bras ou c\u2019est Antonio qui a jug\u00e9 la carotte cuite ?<\/p>\n\n\n\n<p>Venons en \u00e0 l\u2019analyse !<\/p>\n\n\n\n<p>Pour rappel, Mamadou Antonio Souar\u00e9 est le Pr\u00e9sident sortant de la FEGUIFOOT. Il est candidat \u00e0 sa propre succession apr\u00e8s 4 ans de gestion. Il devrait avoir moins de soucis \u00e0 se faire et moins d\u2019efforts \u00e0 fournir pour renouveler son mandat si vraiment le bilan de sa gestion \u00e0 la t\u00eate du football Guin\u00e9en \u00e9tait reluisant.<\/p>\n\n\n\n<p>Tout comme en politique, le bilan reste le moyen le plus convaincant et \u00e9loquent pour se maintenir \u00e0 un poste \u00e9lectif. N\u2019emp\u00eache, tout le monde doit battre campagne soit pour d\u00e9fendre son bilan ou pour convaincre \u00e9nergiquement les \u00e9lecteurs \u00e0 essayer une nouvelle comp\u00e9tence. C\u2019est justement ce qu\u2019on avait commenc\u00e9 \u00e0 assister dans la course \u00e0 la pr\u00e9sidence de l\u2019instance dirigeante du football Guin\u00e9en. Mamadou Antonio Souar\u00e9 et Kerfalla Person Camara KPC, sont deux richissimes hommes d\u2019affaires qui se battaient pour occuper le fauteuil. Le premier \u00e9tait le favori et le second le challenger.<\/p>\n\n\n\n<p>Et puisqu\u2019on parle du football, le fair-play est l\u2019un des principes de base. Les deux plus d\u2019autres candidats s\u2019il y en avait, devraient comp\u00e9tir pour avoir le vote de la majorit\u00e9 des membres statutaires de l\u2019organe.<\/p>\n\n\n\n<p>Malheureusement, d\u00e8s les premiers signaux de la volont\u00e9 manifeste de KPC de se m\u00ealer dans la course, des man\u0153uvres de n\u00e9gociations ont commenc\u00e9. De l\u2019ombre \u00e0 la lumi\u00e8re, plusieurs \u00e9changes ont eu lieu pour amener le patron de GUICOPRES \u00e0 se mettre en rang d\u2019oignons derri\u00e8re la candidature d\u2019Antonio Souar\u00e9.<\/p>\n\n\n\n<p>Comme un deal politique, KPC aurait \u00e9t\u00e9 promis de succ\u00e9der \u00e0 Antonio, aussi patron de SAMGBM \u00e0 la t\u00eate de la FEGUIFOOT au terme des quatres (4) prochaines ann\u00e9es. Alors qu\u2019Antonio devrait probablement se retrouver \u00e0 la CAF ( Conf\u00e9d\u00e9ration Africaine de Football). L\u2019entente aurait \u00e9t\u00e9 scell\u00e9e entre les deux \u00e0 la r\u00e9sidence du challenger sise \u00e0 Lambagny, en pr\u00e9sence de grands t\u00e9moins G\u00e9n\u00e9ral Mathurin Bangoura, Pr\u00e9sident de la Ligue Guin\u00e9enne de Football Professionnel (LGFP) et Bouba Sampil, Pr\u00e9sident de l\u2019AS Kaloum. A ce moment pr\u00e9cis, il y a lieu de se poser la question pourquoi Antonio aurait-il souhait\u00e9 le retrait de KPC dans la danse ? De quoi avait-il peur ?<\/p>\n\n\n\n<p>Del\u00e0, le franc-jeu qui est l\u2019essence m\u00eame du sport, n\u2019avait plus son sens. La d\u00e9mocratie du sport a pris un coup bas. Mais comme on le dit souvent : &lt;&lt; Qui ne se reproche de rien, n\u2019a peur de rien &gt;&gt;. Ce qui ne semblait donc pas le cas pour l\u2019actuel Pr\u00e9sident de la FEGUIFOOT dans ce cas de figure.<\/p>\n\n\n\n<p>Quelques temps apr\u00e8s, l\u2019on ignore ce qui a bien pu se passer. KPC est revenu sur sa d\u00e9cision et s\u2019est d\u00e9clar\u00e9 officiellement candidat \u00e0 la pr\u00e9sidence de la F\u00e9d\u00e9ration Guin\u00e9enne de Football. L\u2019annonce au del\u00e0 d\u2019\u00eatre une nouvelle, aurait mis des fourmis dans les jambes d\u2019Antonio Souar\u00e9. La menace \u00e9tait r\u00e9elle et grandissante m\u00eame si on faisait semblant de ne pas avoir du mauvais sang.<\/p>\n\n\n\n<p>L\u2019activation tr\u00e8s vite des machines de campagne en est la preuve. On ne l\u00e9sinait plus les moyens pour tenter d\u2019assurer la continuit\u00e9 \u00e0 Antonio Souar\u00e9. Les communications s\u2019intensifient, les \u0153uvres de l\u2019homme se font exposer partout dans les m\u00e9dias et sur les panneaux publicitaires. Pendant ce temps, ses supporters n\u2019arr\u00eataient pas de jacasser comme une pie dans les coins et recoins de la capitale.<\/p>\n\n\n\n<p>Dans le camp adverse, rien n\u2019\u00e9tait visible sur le terrain. Les choses semblaient se g\u00e9rer dans l\u2019ombre ou du moins les strat\u00e9gies \u00e9taient en train d\u2019\u00eatre d\u00e9finies.<\/p>\n\n\n\n<p>De part et d\u2019autre, chacun misait sur des cartes pour transformer le jeu en sa faveur. \u00c7a aura \u00e9t\u00e9 une f\u00eate de Madame de Pompadour pour les 65 membres statutaires de la f\u00e9d\u00e9ration. En termes d\u2019engagement, des promesses assorties \u00e0 coup des billets de banque ont \u00e9t\u00e9 faite pour certains et m\u00eame de demeure pour d\u2019autres. Ils auraient eu les yeux plus gros que le ventre.<\/p>\n\n\n\n<p>Par del\u00e0, les sir\u00e8nes et trompettes de campagne continuaient \u00e0 faire une montagne dans les rues de Conakry. Il a fallu l\u2019implication personnelle du Pr\u00e9sident Alpha Cond\u00e9 pour calmer les ardeurs et recentrer le d\u00e9bat aupr\u00e8s des \u00e9lecteurs qui sont les membres statutaires de la f\u00e9d\u00e9ration.<\/p>\n\n\n\n<p>Au lendemain des recommandations du Chef de l\u2019Etat, les deux rivaux sont redevenus des agneaux. Des appels \u00e0 la retenue ont \u00e9t\u00e9 lanc\u00e9s et de nouvelles orientations ont \u00e9t\u00e9 donn\u00e9es par les \u00e9quipes de campagne de tous les deux camps. Antonio et KPC se sont m\u00eame retrouv\u00e9s \u00e0 la faveur d\u2019une conf\u00e9rence par l\u2019interm\u00e9diaire du gendarme gouverneur Mathurin Bangoura, Pr\u00e9sident de la LGFP.<\/p>\n\n\n\n<p>Dans les QG, une tr\u00eave a \u00e9t\u00e9 constat\u00e9e et les hostilit\u00e9s ont baiss\u00e9es d\u2019un cran. Ce qui aurait permis aux \u00ab&nbsp;d\u00e9marcheurs&nbsp;\u00bb des deux camps de reconsid\u00e9rer leurs positions pour tenter de rapprocher les deux hommes. A la manette, le nom de Mathurin est encore apparu avec Fodeba Isto Kera, Secr\u00e9taire G\u00e9n\u00e9ral du Minist\u00e8re des Sports. Au bout de moult n\u00e9gociations, le vin de l\u2019entente a \u00e9t\u00e9 servi il ne restait qu\u2019\u00e0 le boire.<\/p>\n\n\n\n<p>Ainsi, le lundi 5 avril 2021, soit 5 jours apr\u00e8s la tenue de l\u2019assembl\u00e9e g\u00e9n\u00e9rale extraordinaire de la FEGUIFOOT, il a \u00e9t\u00e9 officiellement annonc\u00e9 que KPC retire \u00e0 nouveau sa candidature. A-t-il baiss\u00e9 les bras de son plein gr\u00e9 ou lui a-t-on tordu les bras ?<\/p>\n\n\n\n<p>Premi\u00e8rement, m\u00eame si nous n\u2019avons pas la r\u00e9ponse r\u00e9elle \u00e0 ces questions, il faut dire sans risque de se tromper, que KPC n\u2019aura rien perdu. Plut\u00f4t l\u2019annonce de sa candidature a bien jugul\u00e9 le Pr\u00e9sident sortant de la FEGUIFOOT. N\u2019est-ce pas une d\u00e9monstration de force ?<\/p>\n\n\n\n<p>Deuxi\u00e8mement, les deux questions l\u2019une dans l\u2019autre, expriment un compromis am\u00e8re pour le camp de l\u2019actuel pr\u00e9sident. La succession apr\u00e8s son second mandat, aurait \u00e9t\u00e9 assur\u00e9e \u00e0 KPC. Cela serait motiv\u00e9 par une mont\u00e9e probable d\u2019Antonio Souar\u00e9 dans les instances de la CAF. Et si ce r\u00eave ne se r\u00e9alise pas ?<\/p>\n\n\n\n<p>Troisi\u00e8mement, KPC et ses soutiens ont eu raison d\u2019Antonio Souar\u00e9 par rapport \u00e0 sa gestion du football Guin\u00e9en. Car, il n\u2019y avait pas lieu de faire un compromis pour amener KPC \u00e0 se d\u00e9sister si vraiment il \u00e9tait satisfait de son bilan. D\u2019o\u00f9 la question : Antonio a-t-il servi le football Guin\u00e9en ou s\u2019est servi du football Guin\u00e9en durant les 4 ans de sa gestion ?<\/p>\n\n\n\n<p>Quatri\u00e8mement, l\u2019entente entre les deux homme exigerait de donner le poste de premier vice-pr\u00e9sident au camp de KPC. Comment appelle-t-on ce genre de cohabitation en politique ?<\/p>\n\n\n\n<p>Cinqui\u00e8mement, on ne l\u2019apprend \u00e0 personne les deux camps avaient d\u00e9bours\u00e9s de gros magots dans le cadre de la campagne. KPC a-t-il b\u00e9n\u00e9fici\u00e9 d\u2019une compensation de son investissement ou en a-t-il fait d\u2019un sacrifice ?<\/p>\n\n\n\n<p>S\u00e9rieusement, lequel des deux est gagnant dans ce sc\u00e9nario ? En attendant la r\u00e9ponse \u00e0 cette question, les supporters des deux camps qui ont abattu le travail d\u2019Hercule dans le d\u00e9nigrement, l\u2019injure et la calomnie, vont pouvoir prendre conscience pour dor\u00e9navant agir autrement dans un tel film.<\/p>\n\n\n\n<p><strong>Mamoudou Babila KEITA<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0La course entre Antonio et KPC \u00e0 la Pr\u00e9sidence de la F\u00e9d\u00e9ration Guin\u00e9enne de Football (FEGUIFOOT), n\u2019aura \u00e9t\u00e9 qu\u2019un bide au bout du compte. Pourtant, la bataille \u00e9tait bien partie et semblait livrer des sc\u00e9narios \u00e0 l\u2019image d\u2019une s\u00e9rie Am\u00e9ricaine. De part et d\u2019autre, les \u00e9pisodes pr\u00e9sent\u00e9s \u00e9taient de tout feu tout flamme. Mais finalement, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153],"tags":[2009,1786,4311,6718],"class_list":["post-32422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-antonio-souare","tag-feguifoot","tag-kpc","tag-mamoudoubabila-keita"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=32422"}],"version-history":[{"count":1,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32422\/revisions"}],"predecessor-version":[{"id":32423,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32422\/revisions\/32423"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/32424"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=32422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=32422"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=32422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}