{"id":32273,"date":"2021-04-14T15:16:16","date_gmt":"2021-04-14T15:16:16","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=32273"},"modified":"2021-04-14T15:16:19","modified_gmt":"2021-04-14T15:16:19","slug":"koundouno-a-propos-du-proces-dioulde-le-procureur-de-dixinn-a-devoile-davantage-son-caractere-dindividu-malfaisant","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2021\/04\/14\/koundouno-a-propos-du-proces-dioulde-le-procureur-de-dixinn-a-devoile-davantage-son-caractere-dindividu-malfaisant\/","title":{"rendered":"Koundouno \u00e0 propos du proc\u00e8s Diould\u00e9 : \u2018\u2019le Procureur de Dixinn a d\u00e9voil\u00e9 davantage son caract\u00e8re d\u2019individu malfaisant\u2019\u2019"},"content":{"rendered":"\n<p><strong>Dans le proc\u00e8s de M. Amadou Djould\u00e9 Diallo, journaliste, poursuivi pour offense au dictateur alpha Cond\u00e9, le Procureur de Dixinn a d\u00e9voil\u00e9 davantage son caract\u00e8re d\u2019individu malfaisant. Il a montr\u00e9 \u00e0 la face du monde que son souci est loin d\u2019\u00eatre la protection de l\u2019ordre public. Comme l\u2019a d\u00e9clar\u00e9 un des avocats de Amadou Djould\u00e9 Diallo, il est l\u2019incarnation du mal.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>En effet, depuis l\u2019arrestation et la mise en d\u00e9tention provisoire du journaliste, tous les d\u00e9fenseurs&nbsp; de la libert\u00e9 de la presse, de la libert\u00e9 d\u2019expression et de la libert\u00e9 d\u2019opinion ont d\u00e9nonc\u00e9 la violation flagrante de la loi relative \u00e0 la libert\u00e9 de la presse. En d\u00e9pit de sa tentative de justification de cette mesure, le Procureur n\u2019a pu convaincre personne, m\u00eame les plus profanes. Les explications tr\u00e8s techniques et tr\u00e8s pertinentes des avocats de la d\u00e9fense l\u2019ont totalement ridiculis\u00e9. En fin de compte, il a requis une peine de 5.000.000 de francs. Mais chose in\u00e9dite dans un proc\u00e8s p\u00e9nal, ce procureur qui, apr\u00e8s s\u2019\u00eatre oppos\u00e9 avec v\u00e9h\u00e9mence \u00e0 la mise en libert\u00e9 du journaliste, a demand\u00e9 au Tribunal de rendre sa d\u00e9cision seulement trois semaines apr\u00e8s les d\u00e9bats. Cela n\u2019\u00e9tait jamais arriv\u00e9 dans un proc\u00e8s. Le juge fixe de mani\u00e8re souveraine la date \u00e0 laquelle il rend sa d\u00e9cision.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Cette attitude de Sidy Souleymane N\u2019Diaye prouve de mani\u00e8re tr\u00e8s nette qu\u2019il n\u2019est heureux que lorsqu&rsquo;il envoie des citoyens en prison. Dans le dossier de Amadou Djould\u00e9 Diallo, il doit sans doute regretter que le l\u00e9gislateur ne pr\u00e9voit pas de peine privative de libert\u00e9. Sinon, il aurait requis le maximum de cette peine comme il l\u2019a fait dans toutes les affaires concernant des membres du FNDC ou de l\u2019opposition. C\u2019est donc en d\u00e9sespoir de cause qu\u2019il a demand\u00e9 au juge de rendre sa d\u00e9cision apr\u00e8s trois semaines seulement afin que Amadou Djould\u00e9 Diallo soit d\u00e9tenu pendant quinze jours encore, puisqu\u2019il ne pourra plus emp\u00eacher sa lib\u00e9ration.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Ainsi, le Procureur de la R\u00e9publique, en voulant \u00e0 tout prix faire du mal \u00e0 un justiciable, s\u2019est tout simplement couvert de ridicule aux yeux du monde. Cette attitude se comprend ais\u00e9ment dans la mesure o\u00f9 ce Procureur est oblig\u00e9 de tout faire pour b\u00e9n\u00e9ficier de la protection du despote Alpha Cond\u00e9 par son maintien \u00e0 son poste.<\/strong><\/p>\n\n\n\n<p><strong>En effet, il est all\u00e9 tellement loin dans les actes nuisibles contre les militants de la d\u00e9mocratie qu\u2019il ne peut plus faire machine arri\u00e8re. Il est oblig\u00e9 de faire encore plus mal tous les jours. Sa carri\u00e8re de magistrat est li\u00e9e \u00e0 la prise en otage de Alpha Cond\u00e9.&nbsp; Si celui-ci tombe, il tombe avec plus de fracas \u00e0 son tour.&nbsp; Beaucoup de magistrats se m\u00e9fient d\u00e9sormais des dossiers concernant les membres du FNDC ou de l\u2019opposition \u00e0 cause des pressions qui sont exerc\u00e9es sur eux par le dictateur Alpha Cond\u00e9. Il n\u2019y a que des magistrats qui ont des tendances suicidaires comme Sidy Souleymane N\u2019Diaye qui continuent encore \u00e0 s\u2019int\u00e9resser \u00e0 ces dossiers. Mais on attend la fin du film comme on le dit de mani\u00e8re triviale.<\/strong><\/p>\n\n\n\n<p><strong>S\u00e9kou Koundouno responsable des strat\u00e9gies et planification du FNDC \/Membre Balai Citoyen \/Membre AFRIKKI<\/strong><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le proc\u00e8s de M. Amadou Djould\u00e9 Diallo, journaliste, poursuivi pour offense au dictateur alpha Cond\u00e9, le Procureur de Dixinn a d\u00e9voil\u00e9 davantage son caract\u00e8re d\u2019individu malfaisant. Il a montr\u00e9 \u00e0 la face du monde que son souci est loin d\u2019\u00eatre la protection de l\u2019ordre public. Comme l\u2019a d\u00e9clar\u00e9 un des avocats de Amadou Djould\u00e9 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":26741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[6672,6673],"class_list":["post-32273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-koundouno","tag-procureur-de-dixinn"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=32273"}],"version-history":[{"count":1,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32273\/revisions"}],"predecessor-version":[{"id":32277,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/32273\/revisions\/32277"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/26741"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=32273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=32273"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=32273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}