{"id":31474,"date":"2021-03-29T14:22:53","date_gmt":"2021-03-29T14:22:53","guid":{"rendered":"http:\/\/www.friaguinee.net\/?p=31474"},"modified":"2021-03-29T14:22:55","modified_gmt":"2021-03-29T14:22:55","slug":"detention-du-journaliste-amadou-dioulde-diallo-des-journalistes-projettent-une-manifestation","status":"publish","type":"post","link":"http:\/\/www.friaguinee.net\/index.php\/2021\/03\/29\/detention-du-journaliste-amadou-dioulde-diallo-des-journalistes-projettent-une-manifestation\/","title":{"rendered":"D\u00e9tention du journaliste Amadou Diould\u00e9 Diallo : des journalistes projettent une manifestation"},"content":{"rendered":"\n<p>Le 27 f\u00e9vrier 2021, le journaliste Amadou Diould\u00e9 Diallo a \u00e9t\u00e9 arr\u00eat\u00e9 et, le 1er mars il a \u00e9t\u00e9 mis sous mandat de d\u00e9p\u00f4t et conduit \u00e0 la Maison centrale de Conakry. Nous, journalistes reporters nous nous sommes retrouv\u00e9s le 13 mars 2021 pour mettre en place un Collectif pour sa lib\u00e9ration.<\/p>\n\n\n\n<p>L\u2019objectif du Collectif de Soutien \u00e0 Amadou Diould\u00e9 Diallo (COSADD) vise \u00e0 d\u00e9fendre le principe de la libert\u00e9 de la presse en Guin\u00e9e \u00e0 travers l\u2019application de la loi L002 portant Libert\u00e9 de la presse en R\u00e9publique Guin\u00e9e.<\/p>\n\n\n\n<p>Notre confr\u00e8re a \u00e9t\u00e9 interpell\u00e9, un mois apr\u00e8s avoir accord\u00e9 un entretien \u00e0 la radio Lynx FM dans l\u2019\u00e9mission \u0152il de Lynx du 21 janvier 2021. Il est poursuivi pour offense au Chef de l\u2019Etat et diffamation.<\/p>\n\n\n\n<p>Amadou Diould\u00e9 Diallo se retrouve en prison alors que les d\u00e9lits de presse sont d\u00e9p\u00e9nalis\u00e9s en r\u00e9publique de Guin\u00e9e.<\/p>\n\n\n\n<p>Ainsi, dans sa d\u00e9marche, le COSADD a rencontr\u00e9 les associations professionnelles de m\u00e9dias (Remigui, AGEPI, UGPLG, SPPG, RSF- GUIN\u00c9E, URTELGUI, AGUIPEL) ainsi que l\u2019INIDH et l\u2019OGDH.<\/p>\n\n\n\n<p>Toutes ces structures se sont engag\u00e9es \u00e0 accompagner le Collectif pour d\u00e9noncer la d\u00e9tention ill\u00e9gale de Amadou Diould\u00e9 Diallo et exiger sa lib\u00e9ration.<\/p>\n\n\n\n<p>Le pr\u00e9sident du Remigui, Azoka Bah a d\u00e9clar\u00e9 : \u00ab Si nous nous laissons faire, demain \u00e7a sera un autre \u00bb.<\/p>\n\n\n\n<p>La secr\u00e9taire g\u00e9n\u00e9rale du SPPG, Diaraye Guirassy : \u00ab&nbsp;On n\u2019a jamais \u00e9t\u00e9 indiff\u00e9rent dans la d\u00e9fense des journalistes \u00bb.<\/p>\n\n\n\n<p>Talib\u00e9 Barry de l\u2019URTELGUI : \u00ab Nous avons \u00e9t\u00e9 de toute les luttes, ce n\u2019est pas aujourd\u2019hui que nous allons d\u00e9roger \u00e0 cette r\u00e8gle \u00bb.<\/p>\n\n\n\n<p>Le pr\u00e9sident de l\u2019AGUIPEL : \u00ab Nous allons nous rejoindre \u00e0 vous et notre solidarit\u00e9 ne manquera pas \u00bb.<\/p>\n\n\n\n<p>Le pr\u00e9sident de l\u2019INIDH, Dr Alya Diaby : \u00ab Pour \u00eatre juste sur le cas de Amadou Diould\u00e9 Diallo, il faut le juger sur la base de la loi sur la libert\u00e9 de la presse&nbsp;\u00bb.<\/p>\n\n\n\n<p>Le vice-pr\u00e9sident de l\u2019OGDH, Me Alpha DS Bah : \u00ab Nous saluons l\u2019engagement du collectif parce qu\u2019il faut int\u00e9resser les hommes de m\u00e9dia autour de cette question de libert\u00e9 de la presse&nbsp;\u00bb.<\/p>\n\n\n\n<p>Au regard de ces diff\u00e9rents engagements, le Collectif d\u00e9cide d\u2019organiser une marche pacifique ce mercredi 31 mars 2021, pour d\u00e9noncer la d\u00e9tention pr\u00e9ventive de notre confr\u00e8re depuis un mois \u00e0 la Maison centrale de Conakry.<\/p>\n\n\n\n<p>A cet effet, une lettre d\u2019information a \u00e9t\u00e9 d\u00e9pos\u00e9e \u00e0 la mairie de Kaloum le vendredi 26 mars 2021.<\/p>\n\n\n\n<p>En ce qui concerne l\u2019itin\u00e9raire de la marche, Bourse du travail, point de d\u00e9part- Mus\u00e9e Sandervalia- Mosqu\u00e9e s\u00e9n\u00e9galaise-Carrefour Banque centrale- Minist\u00e8re de la Justice, point de destination.<\/p>\n\n\n\n<p>A cette occasion, nous invitons l\u2019ensemble des journalistes, des associations professionnelles de m\u00e9dias, des organisations de la Soci\u00e9t\u00e9 de la civile, des ONG de d\u00e9fense des droits Humains \u00e0 se joindre \u00e0 nous pour d\u00e9noncer la violation de la Loi L002 portant sur la libert\u00e9 de la presse en Guin\u00e9e.<\/p>\n\n\n\n<p>Je ne saurai terminer sans citer l\u2019ancien pr\u00e9sident am\u00e9ricain, Thomas Jefferson: \u201c<strong>Si l\u2019on me donnait \u00e0 choisir entre un gouvernement sans journaux ou des journaux sans gouvernement, je n\u2019h\u00e9siterais pas un moment \u00e0 choisir cette derni\u00e8re formule<\/strong>\u201d<\/p>\n\n\n\n<p>Vive la libert\u00e9 de la presse !<\/p>\n\n\n\n<p>Vive la d\u00e9mocratie&nbsp;!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 27 f\u00e9vrier 2021, le journaliste Amadou Diould\u00e9 Diallo a \u00e9t\u00e9 arr\u00eat\u00e9 et, le 1er mars il a \u00e9t\u00e9 mis sous mandat de d\u00e9p\u00f4t et conduit \u00e0 la Maison centrale de Conakry. Nous, journalistes reporters nous nous sommes retrouv\u00e9s le 13 mars 2021 pour mettre en place un Collectif pour sa lib\u00e9ration. L\u2019objectif du Collectif [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31044,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3990],"tags":[6349,6500,247],"class_list":["post-31474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medias","tag-amadou-dioulde-diallo","tag-collectif-des-journalistes","tag-marche"],"_links":{"self":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/31474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/comments?post=31474"}],"version-history":[{"count":2,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/31474\/revisions"}],"predecessor-version":[{"id":31476,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/posts\/31474\/revisions\/31476"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media\/31044"}],"wp:attachment":[{"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/media?parent=31474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/categories?post=31474"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.friaguinee.net\/index.php\/wp-json\/wp\/v2\/tags?post=31474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}